{"id":86467,"date":"2022-12-08T12:03:48","date_gmt":"2022-12-08T05:03:48","guid":{"rendered":"https:\/\/school.dek-d.com\/blog\/?p=86467"},"modified":"2024-12-25T10:27:56","modified_gmt":"2024-12-25T03:27:56","slug":"review-tcas-bio-pp","status":"publish","type":"post","link":"https:\/\/school.dek-d.com\/blog\/review\/review-tcas-bio-pp\/","title":{"rendered":"\u0e23\u0e38\u0e48\u0e19\u0e1e\u0e35\u0e48 \u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e23\u0e32\u0e21\u0e32\u0e2f \u0e41\u0e0a\u0e23\u0e4c\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e04\u0e30\u0e41\u0e19\u0e19 A-Level \u0e0a\u0e35\u0e27\u0e30 70 UP\u00a0"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a <span style=\"color: #f37a01;\"><strong>#Dek68<\/strong><\/span>\u00a0\u0e17\u0e35\u0e48\u0e01\u0e33\u0e25\u0e31\u0e07\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e0a\u0e35\u0e27\u0e30\u0e41\u0e25\u0e30\u0e2d\u0e22\u0e32\u0e01\u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e04\u0e30\u0e41\u0e19\u0e19 A-level \u0e0a\u0e35\u0e27\u0e30\u0e2d\u0e22\u0e39\u0e48 \u0e42\u0e04\u0e49\u0e07\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22\u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49\u0e21\u0e32\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e40\u0e1e\u0e37\u0e48\u0e2d <span style=\"color: #f37a01;\"><strong>\u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e04\u0e30\u0e41\u0e19\u0e19 A-Level \u0e0a\u0e35\u0e27\u0e30<\/strong><\/span> \u0e08\u0e32\u0e01\u0e1e\u0e35\u0e48\u0e1e\u0e35\u0e1e\u0e35 \u0e23\u0e38\u0e48\u0e19\u0e1e\u0e35\u0e48\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e23\u0e32\u0e21\u0e32\u0e2f \u0e44\u0e14\u0e49\u0e40\u0e25\u0e22 \u0e1e\u0e35\u0e48\u0e1e\u0e35\u0e48\u0e1e\u0e35\u0e21\u0e35\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e22\u0e31\u0e07\u0e44\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e15\u0e31\u0e27\u0e2a\u0e2d\u0e1a\u0e1a\u0e49\u0e32\u0e07 \u0e44\u0e1b\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22\u0e04\u0e48\u0e30\u00a0<\/span><\/p>\n\n\n<h2 class=\"has-text-color wp-block-heading\" style=\"color:#005248\"><strong>\u0e01\u0e48\u0e2d\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e2b\u0e49\u0e19\u0e49\u0e2d\u0e07\u0e41\u0e19\u0e30\u0e19\u0e33\u0e15\u0e31\u0e27\u0e01\u0e48\u0e2d\u0e19\u0e40\u0e25\u0e22\u0e04\u0e48\u0e30<\/strong><\/h2>\n\n\n<p><span style=\"font-weight: 400;\">\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e35\u0e04\u0e48\u0e30 <\/span><span style=\"color: #f37a01;\"><b>\u0e0a\u0e19\u0e34\u0e01\u0e32\u0e19\u0e15\u0e4c \u0e40\u0e08\u0e35\u0e22\u0e21\u0e27\u0e07\u0e29\u0e32<\/b><\/span><span style=\"font-weight: 400;\"> \u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e25\u0e48\u0e19 \u0e1e\u0e35\u0e1e\u0e35 \u0e40\u0e23\u0e35\u0e22\u0e19\u0e08\u0e1a\u0e08\u0e32\u0e01<\/span><span style=\"color: #f37a01;\"><b>\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32<\/b><\/span><span style=\"font-weight: 400;\"> \u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e2a\u0e2d\u0e1a\u0e15\u0e34\u0e14<\/span><span style=\"color: #f37a01;\"><b>\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e23\u0e32\u0e21\u0e32\u0e18\u0e34\u0e1a\u0e14\u0e35<\/b><\/span><\/p>\n\n\n<h2 class=\"has-text-color wp-block-heading\" style=\"color:#005248\"><strong>\u0e43\u0e0a\u0e49\u0e40\u0e27\u0e25\u0e32 1 \u0e1b\u0e35\u0e01\u0e47\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e40\u0e02\u0e49\u0e32\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e23\u0e32\u0e21\u0e32\u0e2f \u0e44\u0e14\u0e49<\/strong><\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2022\/12\/pp1-1024x936.jpg\" alt=\"\" class=\"wp-image-86470\" width=\"512\" height=\"468\" srcset=\"https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2022\/12\/pp1-1024x936.jpg 1024w, https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2022\/12\/pp1-300x274.jpg 300w, https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2022\/12\/pp1-768x702.jpg 768w, https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2022\/12\/pp1-1536x1404.jpg 1536w, https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2022\/12\/pp1-2048x1872.jpg 2048w, https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2022\/12\/pp1-696x636.jpg 696w, https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2022\/12\/pp1-1068x976.jpg 1068w, https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2022\/12\/pp1-1920x1755.jpg 1920w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/figure><\/div>\n\n\n<p><span style=\"font-weight: 400;\">\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e32\u0e01\u0e40\u0e02\u0e49\u0e32\u0e04\u0e37\u0e2d<span style=\"color: #f37a01;\"><strong>\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e23\u0e32\u0e21\u0e32\u0e18\u0e34\u0e1a\u0e14\u0e35<\/strong><\/span> \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e27\u0e48\u0e32\u0e04\u0e34\u0e14\u0e27\u0e48\u0e32\u0e04\u0e13\u0e30\u0e19\u0e35\u0e49\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e01\u0e31\u0e1a\u0e40\u0e23\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e41\u0e25\u0e49\u0e27 \u0e41\u0e21\u0e49\u0e42\u0e14\u0e22\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27\u0e08\u0e30\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e16\u0e19\u0e31\u0e14\u0e14\u0e49\u0e32\u0e19\u0e04\u0e33\u0e19\u0e27\u0e19\u0e41\u0e15\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e19\u0e43\u0e08\u0e43\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e2a\u0e32\u0e22\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e08\u0e36\u0e07\u0e04\u0e34\u0e14\u0e27\u0e48\u0e32\u0e16\u0e49\u0e32\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2a\u0e32\u0e22\u0e19\u0e35\u0e49\u0e19\u0e48\u0e32\u0e08\u0e30\u0e21\u0e35 passion \u0e41\u0e25\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16 enjoy \u0e44\u0e14\u0e49\u0e21\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 \u0e0b\u0e36\u0e48\u0e07<span style=\"color: #f37a01;\"><strong>\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e43\u0e19\u0e1b\u0e35 65 \u0e04\u0e30\u0e41\u0e19\u0e19\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e04\u0e37\u0e2d \u0e27\u0e34\u0e0a\u0e32\u0e2a\u0e32\u0e21\u0e31\u0e0d 70% \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e40\u0e25\u0e02 \u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c \u0e40\u0e04\u0e21\u0e35 \u0e0a\u0e35\u0e27\u0e30 \u0e44\u0e17\u0e22 \u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29 \u0e2a\u0e31\u0e07\u0e04\u0e21 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e16\u0e19\u0e31\u0e14\u0e41\u0e1e\u0e17\u0e22\u0e4c 30% \u0e0b\u0e36\u0e48\u0e07\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e19\u0e35\u0e49\u0e43\u0e0a\u0e49\u0e40\u0e27\u0e25\u0e32\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e15\u0e31\u0e27\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 1 \u0e1b\u0e35<\/strong><\/span> \u0e40\u0e23\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e15\u0e49\u0e19\u0e40\u0e21\u0e29\u0e32 \u0e04\u0e37\u0e2d\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e2d\u0e19\u0e1b\u0e34\u0e14\u0e40\u0e17\u0e2d\u0e21\u0e02\u0e36\u0e49\u0e19\u0e21.6 \u0e0b\u0e36\u0e48\u0e07\u0e04\u0e34\u0e14\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e27\u0e25\u0e32\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e41\u0e25\u0e49\u0e27 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e16\u0e49\u0e32\u0e40\u0e23\u0e35\u0e22\u0e19\u0e40\u0e23\u0e47\u0e27\u0e01\u0e27\u0e48\u0e32\u0e19\u0e35\u0e49\u0e19\u0e48\u0e32\u0e25\u0e37\u0e21\u0e2b\u0e21\u0e14 55555 \u0e27\u0e34\u0e0a\u0e32\u0e17\u0e35\u0e48\u0e40\u0e23\u0e34\u0e48\u0e21\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e01\u0e48\u0e2d\u0e19\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e1e\u0e27\u0e01\u0e17\u0e31\u0e01\u0e29\u0e30 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e25\u0e02 \u0e41\u0e25\u0e30\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29 \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e40\u0e22\u0e2d\u0e30\u0e2a\u0e38\u0e14\u0e14\u0e49\u0e27\u0e22 \u0e41\u0e25\u0e49\u0e27\u0e01\u0e47\u0e1a\u0e27\u0e01\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e27\u0e34\u0e17\u0e22\u0e4c\u0e44\u0e1b\u0e2d\u0e35\u0e01 1 \u0e15\u0e31\u0e27 \u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e40\u0e04\u0e21\u0e35\u0e44\u0e1b \u0e40\u0e04\u0e25\u0e35\u0e22\u0e23\u0e4c\u0e17\u0e38\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e43\u0e2b\u0e49\u0e40\u0e2a\u0e23\u0e47\u0e08\u0e01\u0e48\u0e2d\u0e19\u0e40\u0e1b\u0e34\u0e14\u0e40\u0e17\u0e2d\u0e211 \u0e1e\u0e2d\u0e40\u0e1b\u0e34\u0e14\u0e40\u0e17\u0e2d\u0e211 \u0e40\u0e23\u0e34\u0e48\u0e21\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c \u0e2a\u0e48\u0e27\u0e19\u0e0a\u0e35\u0e27\u0e30\u0e2d\u0e48\u0e32\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e40\u0e2d\u0e07\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e44\u0e21\u0e48\u0e2d\u0e22\u0e32\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e41\u0e25\u0e49\u0e27 \u0e44\u0e21\u0e48\u0e19\u0e48\u0e32\u0e17\u0e31\u0e19 555555 \u0e2d\u0e48\u0e32\u0e19\u0e40\u0e19\u0e49\u0e19\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e2a\u0e2a\u0e27\u0e17.\u0e40\u0e25\u0e22 \u0e1e\u0e2d\u0e1b\u0e34\u0e14\u0e40\u0e17\u0e2d\u0e21\u0e15\u0e38\u0e25\u0e32\u0e01\u0e47\u0e40\u0e23\u0e34\u0e48\u0e21\u0e40\u0e23\u0e35\u0e22\u0e19\u0e44\u0e17\u0e22 \u0e2a\u0e31\u0e07\u0e04\u0e21 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e16\u0e19\u0e31\u0e14\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e1e\u0e27\u0e01\u0e15\u0e30\u0e25\u0e38\u0e22\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e27\u0e34\u0e0a\u0e32\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e23\u0e27\u0e21\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e15\u0e30\u0e25\u0e38\u0e22\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e0a\u0e35\u0e27\u0e30\u0e02\u0e2d\u0e07\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e2d\u0e38\u0e49\u0e22&nbsp;<\/span><\/p>\n<h2 class=\"has-text-color\" style=\"color: #005248;\"><strong>\u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e04\u0e30\u0e41\u0e19\u0e19 A-Level \u0e0a\u0e35\u0e27\u0e30 \u0e22\u0e31\u0e07\u0e44\u0e07?<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e0a\u0e35\u0e27\u0e30\u0e21\u0e32\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e15\u0e2d\u0e19\u0e40\u0e1b\u0e34\u0e14\u0e21.6 \u0e40\u0e17\u0e2d\u0e21 1 \u0e40\u0e19\u0e49\u0e19\u0e2d\u0e48\u0e32\u0e19\u0e40\u0e2d\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e2a\u0e2a\u0e27\u0e17. (\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19\u0e04\u0e2d\u0e23\u0e4c\u0e2a\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32) \u0e27\u0e34\u0e18\u0e35\u0e2d\u0e48\u0e32\u0e19\u0e04\u0e37\u0e2d\u0e2d\u0e48\u0e32\u0e19\u0e23\u0e2d\u0e1a\u0e41\u0e23\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e41\u0e25\u0e30\u0e40\u0e08\u0e32\u0e30\u0e25\u0e36\u0e01\u0e01\u0e48\u0e2d\u0e19 \u0e41\u0e25\u0e49\u0e27\u0e23\u0e2d\u0e1a\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e01\u0e47\u0e2d\u0e48\u0e32\u0e19\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e44\u0e21\u0e48\u0e43\u0e2b\u0e49\u0e25\u0e37\u0e21 \u0e40\u0e19\u0e49\u0e19\u0e08\u0e38\u0e14\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e42\u0e14\u0e22\u0e08\u0e14\u0e44\u0e27\u0e49\u0e41\u0e22\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e23\u0e38\u0e1b\u0e40\u0e25\u0e47\u0e01\u0e46 \u0e40\u0e2d\u0e32\u0e43\u0e2b\u0e49\u0e41\u0e21\u0e48\u0e19 \u0e01\u0e48\u0e2d\u0e19\u0e15\u0e30\u0e40\u0e23\u0e34\u0e48\u0e21\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e30\u0e25\u0e38\u0e22\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e15\u0e38\u0e25\u0e32 \u0e41\u0e25\u0e30\u0e17\u0e27\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e17\u0e38\u0e01\u0e1a\u0e17\u0e04\u0e23\u0e48\u0e32\u0e27\u0e46 1 \u0e2a\u0e31\u0e1b\u0e14\u0e32\u0e2b\u0e4c\u0e01\u0e48\u0e2d\u0e19\u0e2a\u0e2d\u0e1a\u0e08\u0e23\u0e34\u0e07<\/span><\/p>\n\n\n<h2 class=\"has-text-color\" style=\"color:#005248\"><strong>\u0e2d\u0e22\u0e32\u0e01\u0e40\u0e01\u0e47\u0e1a\u0e04\u0e30\u0e41\u0e19\u0e19\u0e0a\u0e35\u0e27\u0e30\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49 70 UP \u0e40\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e01\u0e47\u0e1a\u0e1a\u0e17\u0e17\u0e35\u0e48\u0e2d\u0e2d\u0e01\u0e2a\u0e2d\u0e1a\u0e40\u0e22\u0e2d\u0e30\u0e41\u0e25\u0e30\u0e1a\u0e17\u0e17\u0e35\u0e48\u0e0a\u0e2d\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e19\u0e0a\u0e48\u0e27\u0e22\u0e44\u0e14\u0e49<\/strong><\/h2>\n\n\n\n<p><span style=\"font-weight: 400;\">\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e27\u0e30\u0e1a\u0e17\u0e17\u0e35\u0e48\u0e2d\u0e2d\u0e01\u0e2a\u0e2d\u0e1a\u0e40\u0e22\u0e2d\u0e30\u0e40\u0e0a\u0e48\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e43\u0e19\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22&nbsp; \u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e01\u0e47\u0e1a\u0e1a\u0e17\u0e17\u0e35\u0e48\u0e0a\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e08\u0e30\u0e44\u0e14\u0e49\u0e21\u0e35\u0e01\u0e33\u0e25\u0e31\u0e07\u0e43\u0e08\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e48\u0e32\u0e19 5555 \u0e16\u0e49\u0e32\u0e2d\u0e22\u0e32\u0e01\u0e17\u0e33\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e41\u0e19\u0e27\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e40\u0e22\u0e2d\u0e30 \u0e25\u0e2d\u0e07\u0e17\u0e33\u0e17\u0e49\u0e32\u0e22\u0e1a\u0e17\u0e2a\u0e2a\u0e27\u0e17.\u0e01\u0e47\u0e44\u0e14\u0e49 \u0e41\u0e15\u0e48\u0e1e\u0e35\u0e48\u0e01\u0e47\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e17\u0e33\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e17\u0e33\u0e44\u0e21\u0e48\u0e17\u0e31\u0e19 \u0e40\u0e25\u0e22\u0e2d\u0e22\u0e32\u0e01\u0e40\u0e15\u0e37\u0e2d\u0e19\u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e27\u0e48\u0e32\u0e41\u0e1a\u0e48\u0e07\u0e40\u0e27\u0e25\u0e32\u0e14\u0e35\u0e46 \u0e19\u0e30 \u0e15\u0e49\u0e2d\u0e07\u0e40\u0e1c\u0e37\u0e48\u0e2d\u0e40\u0e27\u0e25\u0e32\u0e17\u0e33\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e2d\u0e48\u0e32\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e08\u0e23\u0e34\u0e07\u0e46 \u0e15\u0e49\u0e2d\u0e07\u0e1a\u0e2d\u0e01\u0e27\u0e48\u0e32\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e04\u0e32\u0e14\u0e2b\u0e27\u0e31\u0e07\u0e01\u0e31\u0e1a\u0e0a\u0e35\u0e27\u0e30\u0e21\u0e32\u0e01\u0e02\u0e19\u0e32\u0e14\u0e19\u0e31\u0e49\u0e19 \u0e2d\u0e22\u0e32\u0e01\u0e44\u0e14\u0e49\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 70 \u0e04\u0e30\u0e41\u0e19\u0e19\u0e02\u0e36\u0e49\u0e19\u0e44\u0e1b\u0e08\u0e30\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e16\u0e48\u0e27\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e21\u0e32\u0e01 \u0e0b\u0e36\u0e48\u0e07\u0e04\u0e30\u0e41\u0e19\u0e19\u0e01\u0e47\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e15\u0e32\u0e21\u0e40\u0e1b\u0e49\u0e32 \u0e40\u0e22\u0e48&nbsp;<\/span><\/p>\n\n\n<h2 class=\"has-text-color\" style=\"color: #005248;\"><strong>#Dek68 \u0e17\u0e35\u0e48\u0e01\u0e33\u0e25\u0e31\u0e07\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e0a\u0e35\u0e27\u0e30 \u0e04\u0e2d\u0e23\u0e4c\u0e2a\u0e15\u0e30\u0e25\u0e38\u0e22\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e2d.\u0e2d\u0e38\u0e49\u0e22 \u0e0a\u0e48\u0e27\u0e22 \u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e04\u0e30\u0e41\u0e19\u0e19 A-level \u0e0a\u0e35\u0e27\u0e30 \u0e44\u0e14\u0e49<\/strong><\/h2>\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2022\/12\/S__19521542-1024x743.jpg\" alt=\"\u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e04\u0e30\u0e41\u0e19\u0e19 A-LEVEL \u0e0a\u0e35\u0e27\u0e30\" class=\"wp-image-86471\" width=\"512\" height=\"372\" srcset=\"https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2022\/12\/S__19521542-1024x743.jpg 1024w, https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2022\/12\/S__19521542-300x218.jpg 300w, https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2022\/12\/S__19521542-768x557.jpg 768w, https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2022\/12\/S__19521542-696x505.jpg 696w, https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2022\/12\/S__19521542-1068x775.jpg 1068w, https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2022\/12\/S__19521542.jpg 1502w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/figure><\/div>\n\n\n<p><span style=\"color: #f37a01;\"><b>\u0e04\u0e2d\u0e23\u0e4c\u0e2a\u0e02\u0e2d\u0e07\u0e2d.\u0e2d\u0e38\u0e49\u0e22\u0e01\u0e47\u0e14\u0e35\u0e21\u0e32\u0e01\u0e46 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e27\u0e48\u0e32\u0e21\u0e35\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e48\u0e07\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19 \u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e1e\u0e32\u0e40\u0e23\u0e32\u0e40\u0e01\u0e47\u0e1a\u0e44\u0e1b\u0e17\u0e35\u0e25\u0e30\u0e2a\u0e48\u0e27\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e49\u0e2d\u0e2a\u0e2d\u0e1a\u0e43\u0e2b\u0e21\u0e48\u0e17\u0e35\u0e48\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e2d\u0e2d\u0e01\u0e40\u0e2d\u0e07\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u0e0b\u0e36\u0e48\u0e07\u0e2b\u0e21\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e08\u0e2d\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u0e44\u0e2b\u0e19\u0e2d\u0e35\u0e01\u0e41\u0e25\u0e49\u0e27!!!<\/b><\/span><span style=\"font-weight: 400;\"> \u0e41\u0e25\u0e30\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e17\u0e33\u0e19\u0e31\u0e49\u0e19\u0e40\u0e19\u0e49\u0e19\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e0b\u0e36\u0e48\u0e07\u0e15\u0e23\u0e07\u0e01\u0e31\u0e1a\u0e02\u0e49\u0e2d\u0e2a\u0e2d\u0e1a\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e32\u0e01 \u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e04\u0e2d\u0e23\u0e4c\u0e2a\u0e19\u0e35\u0e49\u0e15\u0e2d\u0e1a\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e2a\u0e38\u0e14\u0e46 \u0e01\u0e31\u0e1a\u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e2d\u0e22\u0e32\u0e01 \u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e04\u0e30\u0e41\u0e19\u0e19 A-LEVEL \u0e0a\u0e35\u0e27\u0e30<\/span><\/p>\n\n\n<h2 class=\"has-text-color wp-block-heading\" style=\"color:#005248\"><strong>\u0e2d\u0e22\u0e32\u0e01\u0e17\u0e33\u0e02\u0e49\u0e2d\u0e2a\u0e2d\u0e1a\u0e0a\u0e35\u0e27\u0e30\u0e41\u0e1a\u0e1a\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e44\u0e14\u0e49\u0e15\u0e49\u0e2d\u0e07\u0e41\u0e21\u0e48\u0e19\u0e17\u0e24\u0e29\u0e0e\u0e35<\/strong><\/h2>\n\n\n<p><span style=\"font-weight: 400;\">\u0e02\u0e49\u0e2d\u0e2a\u0e2d\u0e1a\u0e0a\u0e35\u0e27\u0e30\u0e1b\u0e35 65 \u0e41\u0e21\u0e49\u0e08\u0e30\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e04\u0e25\u0e49\u0e32\u0e22\u0e04\u0e25\u0e36\u0e07\u0e01\u0e31\u0e1a\u0e02\u0e49\u0e2d\u0e2a\u0e2d\u0e1a\u0e1b\u0e35 64 \u0e41\u0e15\u0e48\u0e40\u0e19\u0e49\u0e19\u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e35\u0e48\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e40\u0e04\u0e22\u0e2d\u0e2d\u0e01\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e01\u0e04\u0e48\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e07\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e41\u0e25\u0e30\u0e25\u0e36\u0e01\u0e01\u0e27\u0e48\u0e32 \u0e1a\u0e32\u0e07\u0e02\u0e49\u0e2d\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e35\u0e04\u0e27\u0e32\u0e21\u0e08\u0e32\u0e01\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e44\u0e14\u0e49 \u0e41\u0e15\u0e48\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e41\u0e21\u0e48\u0e19\u0e17\u0e24\u0e29\u0e0e\u0e35\u0e01\u0e48\u0e2d\u0e19\u0e16\u0e36\u0e07\u0e08\u0e30\u0e17\u0e33\u0e02\u0e49\u0e2d\u0e2a\u0e2d\u0e1a\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e44\u0e14\u0e49\u0e14\u0e35\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e08\u0e30\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22\u0e02\u0e36\u0e49\u0e19 \u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e2d\u0e48\u0e32\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e43\u0e2b\u0e49\u0e41\u0e21\u0e48\u0e19\u0e41\u0e25\u0e30\u0e1d\u0e36\u0e01\u0e01\u0e32\u0e23\u0e04\u0e34\u0e14\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49&nbsp;<\/span><\/p>\n\n\n<h2 class=\"has-text-color wp-block-heading\" style=\"color:#005248\"><strong>\u0e41\u0e0a\u0e23\u0e4c\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e19\u0e49\u0e2d\u0e07\u0e1e\u0e35\u0e1e\u0e35<\/strong><\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2022\/12\/6B0E81C4-EB00-464D-9643-EB91A664C07D-768x1024.jpg\" alt=\"\u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e04\u0e30\u0e41\u0e19\u0e19 A-LEVEL \u0e0a\u0e35\u0e27\u0e30\" class=\"wp-image-86472\" width=\"384\" height=\"512\" srcset=\"https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2022\/12\/6B0E81C4-EB00-464D-9643-EB91A664C07D-768x1024.jpg 768w, https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2022\/12\/6B0E81C4-EB00-464D-9643-EB91A664C07D-225x300.jpg 225w, https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2022\/12\/6B0E81C4-EB00-464D-9643-EB91A664C07D-696x928.jpg 696w, https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2022\/12\/6B0E81C4-EB00-464D-9643-EB91A664C07D-1068x1425.jpg 1068w, https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2022\/12\/6B0E81C4-EB00-464D-9643-EB91A664C07D.jpg 1108w\" sizes=\"auto, (max-width: 384px) 100vw, 384px\" \/><\/figure><\/div>\n\n\n<p><span style=\"color: #f37a01;\"><b>\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e04\u0e34\u0e14\u0e27\u0e48\u0e32\u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e44\u0e21\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e40\u0e17\u0e48\u0e32\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49<\/b><\/span><span style=\"font-weight: 400;\"> \u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27\u0e08\u0e30\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e27\u0e31\u0e19\u0e25\u0e30 7-8 \u0e0a\u0e21. \u0e41\u0e1a\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e0a\u0e49\u0e32 (\u0e44\u0e21\u0e48\u0e21\u0e32\u0e015555) -\u0e40\u0e17\u0e35\u0e48\u0e22\u0e07 \u0e1a\u0e48\u0e32\u0e22-\u0e40\u0e22\u0e47\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e25\u0e32\u0e07\u0e04\u0e37\u0e19\u0e40\u0e17\u0e48\u0e32\u0e17\u0e35\u0e48\u0e44\u0e2b\u0e27 \u0e1e\u0e2d\u0e40\u0e23\u0e34\u0e48\u0e21\u0e40\u0e2b\u0e19\u0e37\u0e48\u0e2d\u0e22\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e2b\u0e23\u0e48\u0e01\u0e47\u0e08\u0e30\u0e1e\u0e31\u0e01\u0e41\u0e1b\u0e1a\u0e19\u0e36\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e44\u0e21\u0e48\u0e40\u0e01\u0e34\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e23 burn out \u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e04\u0e2d\u0e23\u0e4c\u0e2a\u0e15\u0e30\u0e25\u0e38\u0e22\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e0a\u0e35\u0e27\u0e30\u0e17\u0e35\u0e48\u0e40\u0e23\u0e35\u0e22\u0e19\u0e19\u0e35\u0e49\u0e08\u0e30\u0e40\u0e23\u0e35\u0e22\u0e19\u0e27\u0e31\u0e19\u0e40\u0e27\u0e49\u0e19\u0e27\u0e31\u0e19\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e27\u0e48\u0e32\u0e08\u0e30\u0e17\u0e33\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e17\u0e27\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e01\u0e48\u0e2d\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e19\u0e27\u0e31\u0e19\u0e16\u0e31\u0e14\u0e44\u0e1b\u0e08\u0e30\u0e1f\u0e31\u0e07\u0e40\u0e09\u0e25\u0e22 \u0e40\u0e23\u0e35\u0e22\u0e19\u0e44\u0e1b\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e22\u0e46 \u0e08\u0e19\u0e08\u0e1a\u0e04\u0e2d\u0e23\u0e4c\u0e2a&nbsp;<\/span><\/p>\n\n\n<h2 class=\"has-text-color wp-block-heading\" style=\"color:#005248\"><strong>\u0e01\u0e32\u0e23\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e15\u0e31\u0e27\u0e2a\u0e2d\u0e1a\u0e17\u0e35\u0e48\u0e14\u0e35\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e08\u0e32\u0e01\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19<\/strong><\/h2>\n\n\n<p><span style=\"font-weight: 400;\">\u0e01\u0e32\u0e23\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e15\u0e31\u0e27\u0e2a\u0e2d\u0e1a\u0e04\u0e34\u0e14\u0e27\u0e48\u0e32\u0e04\u0e27\u0e23\u0e40\u0e23\u0e34\u0e48\u0e21\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e43\u0e2b\u0e49\u0e14\u0e35\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e27\u0e48\u0e32\u0e08\u0e30\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e40\u0e2b\u0e19\u0e37\u0e48\u0e2d\u0e22\u0e21\u0e32\u0e01\u0e15\u0e2d\u0e19\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e15\u0e31\u0e27\u0e2a\u0e2d\u0e1a \u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e41\u0e04\u0e48\u0e23\u0e37\u0e49\u0e2d\u0e1f\u0e37\u0e49\u0e19\u0e04\u0e27\u0e32\u0e21\u0e17\u0e23\u0e07\u0e08\u0e33 \u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e43\u0e2b\u0e21\u0e48\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e01\u0e47\u0e41\u0e04\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e21\u0e48\u0e33\u0e40\u0e2a\u0e21\u0e2d\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33 \u0e2d\u0e32\u0e08\u0e08\u0e30\u0e41\u0e04\u0e48\u0e27\u0e31\u0e19\u0e25\u0e30\u0e19\u0e34\u0e14\u0e41\u0e15\u0e48\u0e1e\u0e2d\u0e21\u0e32\u0e2a\u0e30\u0e2a\u0e21\u0e01\u0e31\u0e19\u0e01\u0e47\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e43\u0e19\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e27\u0e32\u0e07\u0e44\u0e27\u0e49\u0e44\u0e14\u0e49&nbsp;<\/span><\/p>\n\n<h2 class=\"has-text-color\" style=\"color: #005248;\"><strong>\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22\u0e19\u0e35\u0e49\u0e2d\u0e22\u0e32\u0e01\u0e43\u0e2b\u0e49\u0e1d\u0e32\u0e01\u0e16\u0e36\u0e07\u0e19\u0e49\u0e2d\u0e07\u0e46 #Dek68 \u0e2b\u0e19\u0e48\u0e2d\u0e22\u0e04\u0e48\u0e30<\/strong><\/h2>\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2022\/12\/pp2-962x1024.jpg\" alt=\"\u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e04\u0e30\u0e41\u0e19\u0e19 A-LEVEL \u0e0a\u0e35\u0e27\u0e30\" class=\"wp-image-86473\" width=\"481\" height=\"512\" srcset=\"https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2022\/12\/pp2-962x1024.jpg 962w, https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2022\/12\/pp2-282x300.jpg 282w, https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2022\/12\/pp2-768x817.jpg 768w, https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2022\/12\/pp2-1443x1536.jpg 1443w, https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2022\/12\/pp2-1924x2048.jpg 1924w, https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2022\/12\/pp2-696x741.jpg 696w, https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2022\/12\/pp2-1068x1137.jpg 1068w, https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2022\/12\/pp2-1920x2043.jpg 1920w\" sizes=\"auto, (max-width: 481px) 100vw, 481px\" \/><\/figure><\/div>\n\n\n<p><span style=\"font-weight: 400;\">\u0e02\u0e2d\u0e43\u0e2b\u0e49\u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e2d\u0e14\u0e17\u0e19 \u0e17\u0e48\u0e2d\u0e07\u0e44\u0e27\u0e49\u0e27\u0e48\u0e32\u0e1e\u0e2d\u0e2a\u0e2d\u0e1a\u0e40\u0e2a\u0e23\u0e47\u0e08\u0e40\u0e23\u0e32\u0e08\u0e30\u0e27\u0e48\u0e32\u0e07\u0e40\u0e15\u0e47\u0e21\u0e46 \u0e2d\u0e35\u0e01 5 \u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e04\u0e48\u0e2d\u0e22\u0e44\u0e1b\u0e1e\u0e31\u0e01\u0e1c\u0e48\u0e2d\u0e19\u0e40\u0e27\u0e25\u0e32\u0e19\u0e31\u0e49\u0e19\u0e01\u0e47\u0e44\u0e14\u0e49 \u0e15\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e1e\u0e22\u0e32\u0e22\u0e32\u0e21\u0e43\u0e2b\u0e49\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e41\u0e25\u0e30\u0e40\u0e2d\u0e32\u0e43\u0e08\u0e43\u0e2a\u0e48\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e41\u0e25\u0e30\u0e08\u0e34\u0e15\u0e43\u0e08\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e14\u0e49\u0e27\u0e22 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e08\u0e38\u0e14\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e25\u0e2d\u0e07\u0e14\u0e39\u0e2a\u0e31\u0e01\u0e04\u0e23\u0e31\u0e49\u0e07 \u0e40\u0e23\u0e32\u0e44\u0e21\u0e48\u0e21\u0e35\u0e17\u0e32\u0e07\u0e23\u0e39\u0e49\u0e27\u0e48\u0e32\u0e08\u0e30\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e21\u0e31\u0e49\u0e22 \u0e16\u0e49\u0e32\u0e44\u0e21\u0e48\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e41\u0e15\u0e48\u0e40\u0e15\u0e47\u0e21\u0e17\u0e35\u0e48\u0e01\u0e31\u0e1a\u0e21\u0e31\u0e19\u0e01\u0e47\u0e08\u0e30\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e40\u0e2a\u0e35\u0e22\u0e43\u0e08\u0e21\u0e32\u0e01 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e14\u0e47\u0e01\u0e0b\u0e34\u0e48\u0e27\u0e1b\u0e35\u0e19\u0e35\u0e49\u0e01\u0e47\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e15\u0e47\u0e21\u0e17\u0e35\u0e48\u0e19\u0e33\u0e02\u0e49\u0e2d\u0e1c\u0e34\u0e14\u0e1e\u0e25\u0e32\u0e14\u0e43\u0e19\u0e1b\u0e35\u0e01\u0e48\u0e2d\u0e19\u0e21\u0e32\u0e1b\u0e23\u0e31\u0e1a\u0e43\u0e0a\u0e49 \u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e27\u0e48\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e22\u0e32\u0e22\u0e32\u0e21\u0e08\u0e30\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e14\u0e35\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19 \u0e2d\u0e4b\u0e2d \u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e21\u0e32\u0e01\u0e46\u0e46\u0e46 \u0e17\u0e35\u0e48\u0e2d\u0e22\u0e32\u0e01\u0e22\u0e49\u0e33\u0e2d\u0e35\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e19\u0e36\u0e07\u0e04\u0e37\u0e2d \u0e01\u0e32\u0e23\u0e21\u0e35\u0e2a\u0e15\u0e34\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e2d\u0e1a \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e23\u0e32\u0e04\u0e34\u0e14\u0e27\u0e48\u0e32\u0e2a\u0e15\u0e34\u0e2a\u0e33\u0e04\u0e31\u0e0d 50% \u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e2d\u0e35\u0e01 50% \u0e40\u0e25\u0e22 \u0e16\u0e49\u0e32\u0e40\u0e23\u0e32\u0e2a\u0e15\u0e34\u0e41\u0e15\u0e01\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e2d\u0e1a\u0e17\u0e38\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e21\u0e32\u0e08\u0e30\u0e1e\u0e31\u0e07\u0e44\u0e1b\u0e2b\u0e21\u0e14 \u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19\u0e02\u0e2d\u0e43\u0e2b\u0e49\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e43\u0e19\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07 \u0e43\u0e19\u0e0a\u0e49\u0e2d\u0e22\u0e2a\u0e4c\u0e17\u0e35\u0e48\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01 \u0e02\u0e2d\u0e43\u0e2b\u0e49\u0e17\u0e38\u0e01\u0e04\u0e19\u0e42\u0e0a\u0e04\u0e14\u0e35\u0e19\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e21\u0e2b\u0e27\u0e31\u0e07\u0e43\u0e19\u0e04\u0e13\u0e30\u0e17\u0e35\u0e48\u0e15\u0e31\u0e49\u0e07\u0e43\u0e08\u0e19\u0e30<\/span><span style=\"font-weight: 400;\"><br \/><\/span><\/p>\n<hr \/>\n<p><span style=\"font-weight: 400;\">\u0e2d\u0e48\u0e32\u0e19\u0e21\u0e32\u0e16\u0e36\u0e07\u0e15\u0e23\u0e07\u0e19\u0e35\u0e49\u0e41\u0e25\u0e49\u0e27\u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e01\u0e47\u0e19\u0e48\u0e32\u0e08\u0e30\u0e44\u0e14\u0e49\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e41\u0e25\u0e30\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14\u0e14\u0e35\u0e46 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e08\u0e32\u0e01\u0e1e\u0e35\u0e48\u0e1e\u0e35\u0e1e\u0e35\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e1e\u0e35\u0e48\u0e1e\u0e35\u0e1e\u0e35\u0e22\u0e49\u0e33\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22\u0e04\u0e37\u0e2d \u0e15\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e21\u0e32\u0e01\u0e41\u0e04\u0e48\u0e44\u0e2b\u0e19\u0e01\u0e47\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e2a\u0e15\u0e34\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22 <\/span><span style=\"font-weight: 400;\">\u0e41\u0e25\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e2d\u0e22\u0e32\u0e01\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e0a\u0e35\u0e27\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e15\u0e34\u0e27\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e01\u0e31\u0e1a \u0e2d.\u0e2d\u0e38\u0e49\u0e22 \u0e14\u0e23.\u0e28\u0e38\u0e20\u0e13\u0e31\u0e10 \u0e44\u0e1e\u0e42\u0e23\u0e2b\u0e01\u0e38\u0e25 \u0e44\u0e14\u0e49\u0e40\u0e25\u0e22 <span style=\"color: #f37a01;\"><a style=\"color: #f37a01;\" href=\"https:\/\/school.dek-d.com\/course\/83\" target=\"_blank\" rel=\"noopener\"><strong>\u0e04\u0e2d\u0e23\u0e4c\u0e2a\u0e1e\u0e34\u0e0a\u0e34\u0e15 TCAS \u0e0a\u0e35\u0e27\u0e30 \u2013 \u0e15\u0e30\u0e25\u0e38\u0e22\u0e42\u0e08\u0e17\u0e22\u0e4c A-Level<\/strong><\/a><\/span> \u0e04\u0e2d\u0e23\u0e4c\u0e2a\u0e19\u0e35\u0e49\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e08\u0e30\u0e44\u0e14\u0e49\u0e15\u0e30\u0e25\u0e38\u0e22\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e0a\u0e35\u0e27\u0e30 \u0e41\u0e19\u0e27\u0e02\u0e49\u0e2d\u0e2a\u0e2d\u0e1a\u0e2d\u0e2d\u0e01\u0e43\u0e2b\u0e21\u0e48 665 \u0e02\u0e49\u0e2d\u0e41\u0e25\u0e49\u0e27 \u0e2d.\u0e2d\u0e38\u0e49\u0e22\u0e22\u0e31\u0e07\u0e40\u0e09\u0e25\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e08\u0e31\u0e14\u0e40\u0e15\u0e47\u0e21 \u0e44\u0e21\u0e48\u0e21\u0e35\u0e02\u0e49\u0e32\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e44\u0e14\u0e49\u0e17\u0e1a\u0e17\u0e27\u0e19 \u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e01\u0e32\u0e23\u0e17\u0e33\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e41\u0e1a\u0e1a\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e41\u0e25\u0e30\u0e1d\u0e36\u0e01\u0e17\u0e33\u0e02\u0e49\u0e2d\u0e2a\u0e2d\u0e1a\u0e01\u0e48\u0e2d\u0e19\u0e25\u0e07\u0e2a\u0e19\u0e32\u0e21\u0e08\u0e23\u0e34\u0e07\u0e14\u0e49\u0e27\u0e22<\/span><\/p>\n<p>\u00a0<\/p>\n\n\n<iframe class=\"course-item-embed\" src=\"https:\/\/school.dek-d.com\/embed\/course\/83\" style=\"display:block; margin: 20px auto 30px; width: 100%; border:none; overflow:hidden; min-height: 160px;\"><\/iframe>\n\n\n<p>\u0e17\u0e38\u0e01\u0e46 \u0e04\u0e2d\u0e23\u0e4c\u0e2a\u0e17\u0e35\u0e48\u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e15\u0e34\u0e27\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e01\u0e31\u0e1a&nbsp;<span style=\"color: #f37a01;\"><a style=\"color: #f37a01;\" href=\"https:\/\/school.dek-d.com\/\" target=\"_blank\" rel=\"noopener\"><b>Dek-D School<\/b><\/a><\/span>&nbsp;\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e27\u0e19\u0e0b\u0e49\u0e33\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e08\u0e33\u0e01\u0e31\u0e14\u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07\u0e15\u0e25\u0e2d\u0e14 6 \u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e17\u0e35\u0e48 \u0e2d.\u0e2d\u0e38\u0e49\u0e22\u0e40\u0e02\u0e35\u0e22\u0e19\u0e2a\u0e48\u0e07\u0e15\u0e23\u0e07\u0e16\u0e36\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e1f\u0e23\u0e35! \u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e41\u0e21\u0e49\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e15\u0e48\u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e2d\u0e1a\u0e16\u0e32\u0e21\u0e02\u0e49\u0e2d\u0e2a\u0e07\u0e2a\u0e31\u0e22\u0e01\u0e31\u0e1a \u0e2d.\u0e2d\u0e38\u0e49\u0e22\u0e43\u0e15\u0e49\u0e04\u0e25\u0e34\u0e1b\u0e17\u0e35\u0e48\u0e01\u0e33\u0e25\u0e31\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e44\u0e14\u0e49 \u0e42\u0e14\u0e22\u0e08\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e41\u0e08\u0e49\u0e07\u0e40\u0e15\u0e37\u0e2d\u0e19\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e21\u0e35\u0e01\u0e32\u0e23\u0e15\u0e2d\u0e1a\u0e01\u0e25\u0e31\u0e1a<\/p>\n<p>\u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e2a\u0e19\u0e43\u0e08\u0e2d\u0e22\u0e32\u0e01\u0e15\u0e34\u0e27\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e01\u0e31\u0e1a&nbsp;<span style=\"color: #f37a01;\"><a style=\"color: #f37a01;\" href=\"https:\/\/school.dek-d.com\/\" target=\"_blank\" rel=\"noopener\"><b>Dek-D School<\/b><\/a>&nbsp;<\/span>\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e35\u0e48\u0e46 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48 Line&nbsp;<span style=\"color: #f37a01;\"><a style=\"color: #f37a01;\" href=\"https:\/\/page.line.me\/quh3207q?openQrModal=true\" target=\"_blank\" rel=\"noopener\"><b>@SchoolDekD<\/b><\/a><\/span>&nbsp;\u0e2b\u0e23\u0e37\u0e2d \u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e01\u0e32\u0e23\u0e15\u0e34\u0e27\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21 \u0e44\u0e14\u0e49\u0e17\u0e35\u0e48&nbsp;<span style=\"color: #f37a01;\"><a style=\"color: #f37a01;\" href=\"https:\/\/www.facebook.com\/schooldekd\" target=\"_blank\" rel=\"noopener\"><b>Facebook Dek-D School<\/b><\/a><\/span>&nbsp;\u0e40\u0e25\u0e22\u0e19\u0e30\u0e04\u0e30<\/p>","protected":false},"excerpt":{"rendered":"<p>\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a #Dek68\u00a0\u0e17\u0e35\u0e48\u0e01\u0e33\u0e25\u0e31\u0e07\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e0a\u0e35\u0e27\u0e30\u0e41\u0e25\u0e30\u0e2d\u0e22\u0e32\u0e01\u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e04\u0e30\u0e41\u0e19\u0e19 A-level \u0e0a\u0e35\u0e27\u0e30\u0e2d\u0e22\u0e39\u0e48 \u0e42\u0e04\u0e49\u0e07\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22\u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49\u0e21\u0e32\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e40\u0e1e\u0e37\u0e48\u0e2d \u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e04\u0e30\u0e41\u0e19\u0e19 A-Level \u0e0a\u0e35\u0e27\u0e30 \u0e08\u0e32\u0e01\u0e1e\u0e35\u0e48\u0e1e\u0e35\u0e1e\u0e35 \u0e23\u0e38\u0e48\u0e19\u0e1e\u0e35\u0e48\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e23\u0e32\u0e21\u0e32\u0e2f \u0e44\u0e14\u0e49\u0e40\u0e25\u0e22 \u0e1e\u0e35\u0e48\u0e1e\u0e35\u0e48\u0e1e\u0e35\u0e21\u0e35\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e22\u0e31\u0e07\u0e44\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e15\u0e31\u0e27\u0e2a\u0e2d\u0e1a\u0e1a\u0e49\u0e32\u0e07 \u0e44\u0e1b\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22\u0e04\u0e48\u0e30\u00a0 \u0e01\u0e48\u0e2d\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e2b\u0e49\u0e19\u0e49\u0e2d\u0e07\u0e41\u0e19\u0e30\u0e19\u0e33\u0e15\u0e31\u0e27\u0e01\u0e48\u0e2d\u0e19\u0e40\u0e25\u0e22\u0e04\u0e48\u0e30 \u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e35\u0e04\u0e48\u0e30 \u0e0a\u0e19\u0e34\u0e01\u0e32\u0e19\u0e15\u0e4c \u0e40\u0e08\u0e35\u0e22\u0e21\u0e27\u0e07\u0e29\u0e32 \u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e25\u0e48\u0e19 \u0e1e\u0e35\u0e1e\u0e35 \u0e40\u0e23\u0e35\u0e22\u0e19\u0e08\u0e1a\u0e08\u0e32\u0e01\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e2a\u0e2d\u0e1a\u0e15\u0e34\u0e14\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e23\u0e32\u0e21\u0e32\u0e18\u0e34\u0e1a\u0e14\u0e35 \u0e43\u0e0a\u0e49\u0e40\u0e27\u0e25\u0e32 1 \u0e1b\u0e35\u0e01\u0e47\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e40\u0e02\u0e49\u0e32\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e23\u0e32\u0e21\u0e32\u0e2f \u0e44\u0e14\u0e49 \u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e32\u0e01\u0e40\u0e02\u0e49\u0e32\u0e04\u0e37\u0e2d\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e23\u0e32\u0e21\u0e32\u0e18\u0e34\u0e1a\u0e14\u0e35 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e27\u0e48\u0e32\u0e04\u0e34\u0e14\u0e27\u0e48\u0e32\u0e04\u0e13\u0e30\u0e19\u0e35\u0e49\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e01\u0e31\u0e1a\u0e40\u0e23\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e41\u0e25\u0e49\u0e27 \u0e41\u0e21\u0e49\u0e42\u0e14\u0e22\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27\u0e08\u0e30\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e16\u0e19\u0e31\u0e14\u0e14\u0e49\u0e32\u0e19\u0e04\u0e33\u0e19\u0e27\u0e19\u0e41\u0e15\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e19\u0e43\u0e08\u0e43\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e2a\u0e32\u0e22\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e08\u0e36\u0e07\u0e04\u0e34\u0e14\u0e27\u0e48\u0e32\u0e16\u0e49\u0e32\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2a\u0e32\u0e22\u0e19\u0e35\u0e49\u0e19\u0e48\u0e32\u0e08\u0e30\u0e21\u0e35 passion \u0e41\u0e25\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16 enjoy \u0e44\u0e14\u0e49\u0e21\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 \u0e0b\u0e36\u0e48\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e43\u0e19\u0e1b\u0e35 65 \u0e04\u0e30\u0e41\u0e19\u0e19\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e04\u0e37\u0e2d \u0e27\u0e34\u0e0a\u0e32\u0e2a\u0e32\u0e21\u0e31\u0e0d 70% \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e40\u0e25\u0e02 \u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c \u0e40\u0e04\u0e21\u0e35 \u0e0a\u0e35\u0e27\u0e30 \u0e44\u0e17\u0e22 \u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29 \u0e2a\u0e31\u0e07\u0e04\u0e21 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e16\u0e19\u0e31\u0e14\u0e41\u0e1e\u0e17\u0e22\u0e4c 30% \u0e0b\u0e36\u0e48\u0e07\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e19\u0e35\u0e49\u0e43\u0e0a\u0e49\u0e40\u0e27\u0e25\u0e32\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e15\u0e31\u0e27\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 1 \u0e1b\u0e35 \u0e40\u0e23\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e15\u0e49\u0e19\u0e40\u0e21\u0e29\u0e32 [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":86684,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[11,252,100],"tags":[394,213,322,475,242,205,320,366,382],"class_list":{"0":"post-86467","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-featured","8":"category-review","9":"category-recommend","10":"tag-dekdschool-2","11":"tag-tcas","12":"tag-tcas65","13":"tag-tcas66","14":"tag-242","15":"tag-205","16":"tag-320","18":"tag-382"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e23\u0e38\u0e48\u0e19\u0e1e\u0e35\u0e48 \u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e23\u0e32\u0e21\u0e32\u0e2f \u0e41\u0e0a\u0e23\u0e4c\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e04\u0e30\u0e41\u0e19\u0e19 A-LEVEL \u0e0a\u0e35\u0e27\u0e30 70 UP<\/title>\n<meta name=\"description\" content=\"\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a #Dek66 \u0e17\u0e35\u0e2d\u0e22\u0e32\u0e01\u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e04\u0e30\u0e41\u0e19\u0e19 A-level \u0e0a\u0e35\u0e27\u0e30\u0e2d\u0e22\u0e39\u0e48 \u0e21\u0e32\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e40\u0e1e\u0e37\u0e48\u0e2d \u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e04\u0e30\u0e41\u0e19\u0e19 A-Level \u0e0a\u0e35\u0e27\u0e30 \u0e08\u0e32\u0e01\u0e1e\u0e35\u0e48\u0e1e\u0e35\u0e1e\u0e35 \u0e23\u0e38\u0e48\u0e19\u0e1e\u0e35\u0e48\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e23\u0e32\u0e21\u0e32\u0e2f \u0e44\u0e14\u0e49\u0e40\u0e25\u0e22\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/school.dek-d.com\/blog\/review\/review-tcas-bio-pp\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e23\u0e38\u0e48\u0e19\u0e1e\u0e35\u0e48 \u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e23\u0e32\u0e21\u0e32\u0e2f \u0e41\u0e0a\u0e23\u0e4c\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e04\u0e30\u0e41\u0e19\u0e19 A-LEVEL \u0e0a\u0e35\u0e27\u0e30 70 UP\" \/>\n<meta property=\"og:description\" content=\"\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a #Dek66 \u0e17\u0e35\u0e2d\u0e22\u0e32\u0e01\u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e04\u0e30\u0e41\u0e19\u0e19 A-level \u0e0a\u0e35\u0e27\u0e30\u0e2d\u0e22\u0e39\u0e48 \u0e21\u0e32\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e40\u0e1e\u0e37\u0e48\u0e2d \u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e04\u0e30\u0e41\u0e19\u0e19 A-Level \u0e0a\u0e35\u0e27\u0e30 \u0e08\u0e32\u0e01\u0e1e\u0e35\u0e48\u0e1e\u0e35\u0e1e\u0e35 \u0e23\u0e38\u0e48\u0e19\u0e1e\u0e35\u0e48\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e23\u0e32\u0e21\u0e32\u0e2f \u0e44\u0e14\u0e49\u0e40\u0e25\u0e22\" \/>\n<meta property=\"og:url\" content=\"https:\/\/school.dek-d.com\/blog\/review\/review-tcas-bio-pp\/\" \/>\n<meta property=\"og:site_name\" content=\"Dek-D&#039;s School\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kidcoding\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-08T05:03:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-25T03:27:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2022\/12\/og-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"378\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u0e04\u0e23\u0e39\u0e19\u0e49\u0e33\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0e04\u0e23\u0e39\u0e19\u0e49\u0e33\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/school.dek-d.com\/blog\/review\/review-tcas-bio-pp\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/school.dek-d.com\/blog\/review\/review-tcas-bio-pp\/\"},\"author\":{\"name\":\"\u0e04\u0e23\u0e39\u0e19\u0e49\u0e33\",\"@id\":\"https:\/\/school.dek-d.com\/blog\/#\/schema\/person\/e8061732124e911d6d28cc4d8b0a3aeb\"},\"headline\":\"\u0e23\u0e38\u0e48\u0e19\u0e1e\u0e35\u0e48 \u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e23\u0e32\u0e21\u0e32\u0e2f \u0e41\u0e0a\u0e23\u0e4c\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e04\u0e30\u0e41\u0e19\u0e19 A-Level \u0e0a\u0e35\u0e27\u0e30 70 UP\u00a0\",\"datePublished\":\"2022-12-08T05:03:48+00:00\",\"dateModified\":\"2024-12-25T03:27:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/school.dek-d.com\/blog\/review\/review-tcas-bio-pp\/\"},\"wordCount\":43,\"publisher\":{\"@id\":\"https:\/\/school.dek-d.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/school.dek-d.com\/blog\/review\/review-tcas-bio-pp\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2022\/12\/og-2.jpg\",\"keywords\":[\"dekdschool\",\"tcas\",\"TCAS65\",\"TCAS66\",\"\u0e0a\u0e35\u0e27\u0e30\",\"\u0e15\u0e34\u0e27\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\",\"\u0e15\u0e34\u0e27\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e0a\u0e35\u0e27\u0e27\u0e34\u0e17\u0e22\u0e32\",\"\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1aTCAS\",\"\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e0a\u0e35\u0e27\u0e30\"],\"articleSection\":[\"Featured\",\"Review\",\"\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e41\u0e19\u0e30\u0e19\u0e33\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/school.dek-d.com\/blog\/review\/review-tcas-bio-pp\/\",\"url\":\"https:\/\/school.dek-d.com\/blog\/review\/review-tcas-bio-pp\/\",\"name\":\"\u0e23\u0e38\u0e48\u0e19\u0e1e\u0e35\u0e48 \u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e23\u0e32\u0e21\u0e32\u0e2f \u0e41\u0e0a\u0e23\u0e4c\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e04\u0e30\u0e41\u0e19\u0e19 A-LEVEL \u0e0a\u0e35\u0e27\u0e30 70 UP\",\"isPartOf\":{\"@id\":\"https:\/\/school.dek-d.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/school.dek-d.com\/blog\/review\/review-tcas-bio-pp\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/school.dek-d.com\/blog\/review\/review-tcas-bio-pp\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2022\/12\/og-2.jpg\",\"datePublished\":\"2022-12-08T05:03:48+00:00\",\"dateModified\":\"2024-12-25T03:27:56+00:00\",\"description\":\"\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a #Dek66 \u0e17\u0e35\u0e2d\u0e22\u0e32\u0e01\u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e04\u0e30\u0e41\u0e19\u0e19 A-level \u0e0a\u0e35\u0e27\u0e30\u0e2d\u0e22\u0e39\u0e48 \u0e21\u0e32\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e40\u0e1e\u0e37\u0e48\u0e2d \u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e04\u0e30\u0e41\u0e19\u0e19 A-Level \u0e0a\u0e35\u0e27\u0e30 \u0e08\u0e32\u0e01\u0e1e\u0e35\u0e48\u0e1e\u0e35\u0e1e\u0e35 \u0e23\u0e38\u0e48\u0e19\u0e1e\u0e35\u0e48\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e23\u0e32\u0e21\u0e32\u0e2f \u0e44\u0e14\u0e49\u0e40\u0e25\u0e22\",\"breadcrumb\":{\"@id\":\"https:\/\/school.dek-d.com\/blog\/review\/review-tcas-bio-pp\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/school.dek-d.com\/blog\/review\/review-tcas-bio-pp\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/school.dek-d.com\/blog\/review\/review-tcas-bio-pp\/#primaryimage\",\"url\":\"https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2022\/12\/og-2.jpg\",\"contentUrl\":\"https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2022\/12\/og-2.jpg\",\"width\":720,\"height\":378},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/school.dek-d.com\/blog\/review\/review-tcas-bio-pp\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/school.dek-d.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e23\u0e38\u0e48\u0e19\u0e1e\u0e35\u0e48 \u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e23\u0e32\u0e21\u0e32\u0e2f \u0e41\u0e0a\u0e23\u0e4c\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e04\u0e30\u0e41\u0e19\u0e19 A-Level \u0e0a\u0e35\u0e27\u0e30 70 UP\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/school.dek-d.com\/blog\/#website\",\"url\":\"https:\/\/school.dek-d.com\/blog\/\",\"name\":\"\u0e2a\u0e2d\u0e19\u0e25\u0e39\u0e01\u0e40\u0e02\u0e35\u0e22\u0e19\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 By Dek-D.com\",\"description\":\"\u0e04\u0e2d\u0e23\u0e4c\u0e2a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c | \u0e40\u0e01\u0e48\u0e07\u0e01\u0e27\u0e48\u0e32 \u0e14\u0e49\u0e27\u0e22\u0e40\u0e27\u0e25\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e31\u0e49\u0e19\u0e01\u0e27\u0e48\u0e32\",\"publisher\":{\"@id\":\"https:\/\/school.dek-d.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/school.dek-d.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/school.dek-d.com\/blog\/#organization\",\"name\":\"Dek-D Interactive\",\"url\":\"https:\/\/school.dek-d.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/school.dek-d.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2018\/01\/mobile_280x96-1.png\",\"contentUrl\":\"https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2018\/01\/mobile_280x96-1.png\",\"width\":280,\"height\":96,\"caption\":\"Dek-D Interactive\"},\"image\":{\"@id\":\"https:\/\/school.dek-d.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/kidcoding\/\",\"https:\/\/www.youtube.com\/user\/webdekd\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/school.dek-d.com\/blog\/#\/schema\/person\/e8061732124e911d6d28cc4d8b0a3aeb\",\"name\":\"\u0e04\u0e23\u0e39\u0e19\u0e49\u0e33\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/school.dek-d.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ddff52be616465b8b9719aba88a2156c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ddff52be616465b8b9719aba88a2156c?s=96&d=mm&r=g\",\"caption\":\"\u0e04\u0e23\u0e39\u0e19\u0e49\u0e33\"},\"url\":\"https:\/\/school.dek-d.com\/blog\/author\/prapimpan\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e23\u0e38\u0e48\u0e19\u0e1e\u0e35\u0e48 \u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e23\u0e32\u0e21\u0e32\u0e2f \u0e41\u0e0a\u0e23\u0e4c\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e04\u0e30\u0e41\u0e19\u0e19 A-LEVEL \u0e0a\u0e35\u0e27\u0e30 70 UP","description":"\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a #Dek66 \u0e17\u0e35\u0e2d\u0e22\u0e32\u0e01\u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e04\u0e30\u0e41\u0e19\u0e19 A-level \u0e0a\u0e35\u0e27\u0e30\u0e2d\u0e22\u0e39\u0e48 \u0e21\u0e32\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e40\u0e1e\u0e37\u0e48\u0e2d \u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e04\u0e30\u0e41\u0e19\u0e19 A-Level \u0e0a\u0e35\u0e27\u0e30 \u0e08\u0e32\u0e01\u0e1e\u0e35\u0e48\u0e1e\u0e35\u0e1e\u0e35 \u0e23\u0e38\u0e48\u0e19\u0e1e\u0e35\u0e48\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e23\u0e32\u0e21\u0e32\u0e2f \u0e44\u0e14\u0e49\u0e40\u0e25\u0e22","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/school.dek-d.com\/blog\/review\/review-tcas-bio-pp\/","og_locale":"en_US","og_type":"article","og_title":"\u0e23\u0e38\u0e48\u0e19\u0e1e\u0e35\u0e48 \u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e23\u0e32\u0e21\u0e32\u0e2f \u0e41\u0e0a\u0e23\u0e4c\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e04\u0e30\u0e41\u0e19\u0e19 A-LEVEL \u0e0a\u0e35\u0e27\u0e30 70 UP","og_description":"\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a #Dek66 \u0e17\u0e35\u0e2d\u0e22\u0e32\u0e01\u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e04\u0e30\u0e41\u0e19\u0e19 A-level \u0e0a\u0e35\u0e27\u0e30\u0e2d\u0e22\u0e39\u0e48 \u0e21\u0e32\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e40\u0e1e\u0e37\u0e48\u0e2d \u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e04\u0e30\u0e41\u0e19\u0e19 A-Level \u0e0a\u0e35\u0e27\u0e30 \u0e08\u0e32\u0e01\u0e1e\u0e35\u0e48\u0e1e\u0e35\u0e1e\u0e35 \u0e23\u0e38\u0e48\u0e19\u0e1e\u0e35\u0e48\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e23\u0e32\u0e21\u0e32\u0e2f \u0e44\u0e14\u0e49\u0e40\u0e25\u0e22","og_url":"https:\/\/school.dek-d.com\/blog\/review\/review-tcas-bio-pp\/","og_site_name":"Dek-D&#039;s School","article_publisher":"https:\/\/www.facebook.com\/kidcoding\/","article_published_time":"2022-12-08T05:03:48+00:00","article_modified_time":"2024-12-25T03:27:56+00:00","og_image":[{"width":720,"height":378,"url":"https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2022\/12\/og-2.jpg","type":"image\/jpeg"}],"author":"\u0e04\u0e23\u0e39\u0e19\u0e49\u0e33","twitter_card":"summary_large_image","twitter_misc":{"Written by":"\u0e04\u0e23\u0e39\u0e19\u0e49\u0e33","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/school.dek-d.com\/blog\/review\/review-tcas-bio-pp\/#article","isPartOf":{"@id":"https:\/\/school.dek-d.com\/blog\/review\/review-tcas-bio-pp\/"},"author":{"name":"\u0e04\u0e23\u0e39\u0e19\u0e49\u0e33","@id":"https:\/\/school.dek-d.com\/blog\/#\/schema\/person\/e8061732124e911d6d28cc4d8b0a3aeb"},"headline":"\u0e23\u0e38\u0e48\u0e19\u0e1e\u0e35\u0e48 \u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e23\u0e32\u0e21\u0e32\u0e2f \u0e41\u0e0a\u0e23\u0e4c\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e04\u0e30\u0e41\u0e19\u0e19 A-Level \u0e0a\u0e35\u0e27\u0e30 70 UP\u00a0","datePublished":"2022-12-08T05:03:48+00:00","dateModified":"2024-12-25T03:27:56+00:00","mainEntityOfPage":{"@id":"https:\/\/school.dek-d.com\/blog\/review\/review-tcas-bio-pp\/"},"wordCount":43,"publisher":{"@id":"https:\/\/school.dek-d.com\/blog\/#organization"},"image":{"@id":"https:\/\/school.dek-d.com\/blog\/review\/review-tcas-bio-pp\/#primaryimage"},"thumbnailUrl":"https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2022\/12\/og-2.jpg","keywords":["dekdschool","tcas","TCAS65","TCAS66","\u0e0a\u0e35\u0e27\u0e30","\u0e15\u0e34\u0e27\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c","\u0e15\u0e34\u0e27\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e0a\u0e35\u0e27\u0e27\u0e34\u0e17\u0e22\u0e32","\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1aTCAS","\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e0a\u0e35\u0e27\u0e30"],"articleSection":["Featured","Review","\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e41\u0e19\u0e30\u0e19\u0e33"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/school.dek-d.com\/blog\/review\/review-tcas-bio-pp\/","url":"https:\/\/school.dek-d.com\/blog\/review\/review-tcas-bio-pp\/","name":"\u0e23\u0e38\u0e48\u0e19\u0e1e\u0e35\u0e48 \u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e23\u0e32\u0e21\u0e32\u0e2f \u0e41\u0e0a\u0e23\u0e4c\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e04\u0e30\u0e41\u0e19\u0e19 A-LEVEL \u0e0a\u0e35\u0e27\u0e30 70 UP","isPartOf":{"@id":"https:\/\/school.dek-d.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/school.dek-d.com\/blog\/review\/review-tcas-bio-pp\/#primaryimage"},"image":{"@id":"https:\/\/school.dek-d.com\/blog\/review\/review-tcas-bio-pp\/#primaryimage"},"thumbnailUrl":"https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2022\/12\/og-2.jpg","datePublished":"2022-12-08T05:03:48+00:00","dateModified":"2024-12-25T03:27:56+00:00","description":"\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a #Dek66 \u0e17\u0e35\u0e2d\u0e22\u0e32\u0e01\u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e04\u0e30\u0e41\u0e19\u0e19 A-level \u0e0a\u0e35\u0e27\u0e30\u0e2d\u0e22\u0e39\u0e48 \u0e21\u0e32\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e40\u0e1e\u0e37\u0e48\u0e2d \u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e04\u0e30\u0e41\u0e19\u0e19 A-Level \u0e0a\u0e35\u0e27\u0e30 \u0e08\u0e32\u0e01\u0e1e\u0e35\u0e48\u0e1e\u0e35\u0e1e\u0e35 \u0e23\u0e38\u0e48\u0e19\u0e1e\u0e35\u0e48\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e23\u0e32\u0e21\u0e32\u0e2f \u0e44\u0e14\u0e49\u0e40\u0e25\u0e22","breadcrumb":{"@id":"https:\/\/school.dek-d.com\/blog\/review\/review-tcas-bio-pp\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/school.dek-d.com\/blog\/review\/review-tcas-bio-pp\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/school.dek-d.com\/blog\/review\/review-tcas-bio-pp\/#primaryimage","url":"https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2022\/12\/og-2.jpg","contentUrl":"https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2022\/12\/og-2.jpg","width":720,"height":378},{"@type":"BreadcrumbList","@id":"https:\/\/school.dek-d.com\/blog\/review\/review-tcas-bio-pp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/school.dek-d.com\/blog\/"},{"@type":"ListItem","position":2,"name":"\u0e23\u0e38\u0e48\u0e19\u0e1e\u0e35\u0e48 \u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e23\u0e32\u0e21\u0e32\u0e2f \u0e41\u0e0a\u0e23\u0e4c\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e04\u0e30\u0e41\u0e19\u0e19 A-Level \u0e0a\u0e35\u0e27\u0e30 70 UP\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/school.dek-d.com\/blog\/#website","url":"https:\/\/school.dek-d.com\/blog\/","name":"\u0e2a\u0e2d\u0e19\u0e25\u0e39\u0e01\u0e40\u0e02\u0e35\u0e22\u0e19\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 By Dek-D.com","description":"\u0e04\u0e2d\u0e23\u0e4c\u0e2a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c | \u0e40\u0e01\u0e48\u0e07\u0e01\u0e27\u0e48\u0e32 \u0e14\u0e49\u0e27\u0e22\u0e40\u0e27\u0e25\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e31\u0e49\u0e19\u0e01\u0e27\u0e48\u0e32","publisher":{"@id":"https:\/\/school.dek-d.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/school.dek-d.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/school.dek-d.com\/blog\/#organization","name":"Dek-D Interactive","url":"https:\/\/school.dek-d.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/school.dek-d.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2018\/01\/mobile_280x96-1.png","contentUrl":"https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2018\/01\/mobile_280x96-1.png","width":280,"height":96,"caption":"Dek-D Interactive"},"image":{"@id":"https:\/\/school.dek-d.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kidcoding\/","https:\/\/www.youtube.com\/user\/webdekd"]},{"@type":"Person","@id":"https:\/\/school.dek-d.com\/blog\/#\/schema\/person\/e8061732124e911d6d28cc4d8b0a3aeb","name":"\u0e04\u0e23\u0e39\u0e19\u0e49\u0e33","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/school.dek-d.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ddff52be616465b8b9719aba88a2156c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ddff52be616465b8b9719aba88a2156c?s=96&d=mm&r=g","caption":"\u0e04\u0e23\u0e39\u0e19\u0e49\u0e33"},"url":"https:\/\/school.dek-d.com\/blog\/author\/prapimpan\/"}]}},"_links":{"self":[{"href":"https:\/\/school.dek-d.com\/blog\/wp-json\/wp\/v2\/posts\/86467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/school.dek-d.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/school.dek-d.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/school.dek-d.com\/blog\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/school.dek-d.com\/blog\/wp-json\/wp\/v2\/comments?post=86467"}],"version-history":[{"count":7,"href":"https:\/\/school.dek-d.com\/blog\/wp-json\/wp\/v2\/posts\/86467\/revisions"}],"predecessor-version":[{"id":92287,"href":"https:\/\/school.dek-d.com\/blog\/wp-json\/wp\/v2\/posts\/86467\/revisions\/92287"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/school.dek-d.com\/blog\/wp-json\/wp\/v2\/media\/86684"}],"wp:attachment":[{"href":"https:\/\/school.dek-d.com\/blog\/wp-json\/wp\/v2\/media?parent=86467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/school.dek-d.com\/blog\/wp-json\/wp\/v2\/categories?post=86467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/school.dek-d.com\/blog\/wp-json\/wp\/v2\/tags?post=86467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}