{"id":91967,"date":"2024-07-25T13:46:53","date_gmt":"2024-07-25T06:46:53","guid":{"rendered":"https:\/\/school.dek-d.com\/blog\/?p=91967"},"modified":"2024-07-25T13:46:58","modified_gmt":"2024-07-25T06:46:58","slug":"posn-physics-golf","status":"publish","type":"post","link":"https:\/\/school.dek-d.com\/blog\/review\/posn-physics-golf\/","title":{"rendered":"\u0e41\u0e0a\u0e23\u0e4c\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c \u0e15\u0e34\u0e14\u0e04\u0e48\u0e32\u0e22 2 \u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e2d\u0e22\u0e32\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e14\u0e47\u0e01\u0e04\u0e48\u0e32\u0e22\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e15\u0e48\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e23\u0e39\u0e49\u0e08\u0e30\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e15\u0e31\u0e27\u0e22\u0e31\u0e07\u0e44\u0e07\u0e43\u0e2b\u0e49\u0e15\u0e34\u0e14\u0e04\u0e48\u0e32\u0e22\u0e14\u0e35 \u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e42\u0e04\u0e49\u0e07\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22\u0e01\u0e48\u0e2d\u0e19\u0e2a\u0e2d\u0e1a\u0e19\u0e35\u0e49 \u0e21\u0e32\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c \u0e14\u0e48\u0e27\u0e19\u0e46 \u0e08\u0e32\u0e01\u0e1e\u0e35\u0e48\u0e01\u0e2d\u0e25\u0e4c\u0e1f\u0e23\u0e38\u0e48\u0e19\u0e1e\u0e35\u0e48\u0e40\u0e14\u0e47\u0e01\u0e04\u0e48\u0e32\u0e22\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22 \u0e1e\u0e35\u0e48\u0e01\u0e2d\u0e25\u0e4c\u0e1f\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e15\u0e31\u0e27\u0e2a\u0e2d\u0e1a \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23 <\/span><a href=\"https:\/\/school.dek-d.com\/course\/178\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #f37a01;\"><b>\u0e15\u0e34\u0e27\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e04\u0e2d\u0e23\u0e4c\u0e2a\u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c\u0e01\u0e31\u0e1a\u0e2d.\u0e2b\u0e25\u0e34\u0e19 Dek-D School<\/b><\/span><\/a><span style=\"font-weight: 400;\"> \u0e08\u0e19\u0e2a\u0e2d\u0e1a\u0e15\u0e34\u0e14\u0e04\u0e48\u0e32\u0e22 2 \u0e16\u0e49\u0e32\u0e2d\u0e22\u0e32\u0e01\u0e23\u0e39\u0e49\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e41\u0e25\u0e49\u0e27 \u0e44\u0e1b\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22<\/span><\/p>\n\n\n<h2 class=\"has-text-color wp-block-heading\" style=\"color:#005248\"><strong>\u0e01\u0e48\u0e2d\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e2b\u0e49\u0e19\u0e49\u0e2d\u0e07\u0e41\u0e19\u0e30\u0e19\u0e33\u0e15\u0e31\u0e27\u0e01\u0e48\u0e2d\u0e19\u0e04\u0e48\u0e30<\/strong><\/h2>\n\n\n<p><span style=\"font-weight: 400;\">\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e35\u0e04\u0e23\u0e31\u0e1a\u0e1c\u0e21 <\/span><span style=\"color: #f37a01;\"><b>\u0e01\u0e24\u0e15\u0e40\u0e21\u0e18 \u0e07\u0e32\u0e21\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c <\/b><\/span><span style=\"font-weight: 400;\">\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e25\u0e48\u0e19 \u0e01\u0e2d\u0e25\u0e4c\u0e1f \u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e0a\u0e31\u0e49\u0e19\u0e21.6 <\/span><span style=\"color: #f37a01;\"><b>\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e17\u0e38\u0e48\u0e07\u0e2a\u0e07 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a<\/b><\/span><\/p>\n\n\n<h2 class=\"has-text-color wp-block-heading\" style=\"color:#005248\"><strong>\u0e2d\u0e22\u0e32\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e14\u0e47\u0e01\u0e04\u0e48\u0e32\u0e22\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e41\u0e25\u0e30\u0e44\u0e14\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e21\u0e35\u0e2a\u0e2d\u0e19\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19<\/strong><\/h2>\n\n\n<p><span style=\"font-weight: 400;\">\u0e1c\u0e21\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e27\u0e19.\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e2d\u0e01\u0e40\u0e25\u0e48\u0e32\u0e02\u0e2d\u0e07\u0e04\u0e23\u0e39\u0e43\u0e19\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e2d\u0e19\u0e21.4 \u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e2a\u0e2d\u0e27\u0e19.\u0e21\u0e35\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e1a\u0e31\u0e15\u0e23\u0e17\u0e35\u0e48\u0e21\u0e35\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e21\u0e2b\u0e32\u0e25\u0e31\u0e22\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e1c\u0e21\u0e08\u0e36\u0e07\u0e2a\u0e19\u0e43\u0e08\u0e17\u0e35\u0e48\u0e08\u0e30\u0e2a\u0e2d\u0e1a\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e02\u0e2d\u0e07\u0e15\u0e19\u0e40\u0e2d\u0e07 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e1c\u0e21\u0e22\u0e31\u0e07\u0e2d\u0e22\u0e32\u0e01\u0e17\u0e35\u0e48\u0e08\u0e30\u0e44\u0e14\u0e49\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e40\u0e02\u0e49\u0e32\u0e04\u0e48\u0e32\u0e22\u0e2a\u0e2d\u0e27\u0e19.\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e43\u0e19\u0e04\u0e48\u0e32\u0e22\u0e08\u0e30\u0e2d\u0e1a\u0e23\u0e21\u0e43\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e21\u0e35\u0e43\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e1b\u0e01\u0e15\u0e34\u0e17\u0e31\u0e49\u0e07\u0e22\u0e31\u0e07\u0e44\u0e14\u0e49\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e01\u0e31\u0e1a\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e15\u0e48\u0e32\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e0b\u0e36\u0e48\u0e07\u0e01\u0e34\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e2b\u0e25\u0e31\u0e1a\u0e19\u0e2d\u0e19\u0e14\u0e49\u0e27\u0e22\u0e01\u0e31\u0e19\u0e43\u0e19\u0e04\u0e48\u0e32\u0e22<\/span><\/p>\n\n\n<h2 class=\"has-text-color wp-block-heading\" style=\"color:#005248\"><strong>\u0e17\u0e33\u0e44\u0e21\u0e16\u0e36\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2a\u0e2d\u0e1a\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c?<\/strong><\/h2>\n\n\n<p><span style=\"font-weight: 400;\">\u0e1c\u0e21\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e2d\u0e1a\u0e40\u0e40\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e43\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e38\u0e19\u0e40\u0e14\u0e34\u0e21\u0e2d\u0e22\u0e39\u0e48\u0e40\u0e40\u0e25\u0e49\u0e27\u0e08\u0e36\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e27\u0e34\u0e0a\u0e32\u0e19\u0e35\u0e49\u0e41\u0e25\u0e30\u0e27\u0e34\u0e0a\u0e32\u0e19\u0e35\u0e49\u0e01\u0e47\u0e40\u0e19\u0e49\u0e19\u0e01\u0e32\u0e23\u0e04\u0e33\u0e19\u0e27\u0e13\u0e40\u0e40\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e43\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e01\u0e32\u0e23\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e08\u0e33\u0e1c\u0e21\u0e17\u0e35\u0e48\u0e16\u0e19\u0e31\u0e14\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e04\u0e33\u0e19\u0e27\u0e13\u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e04\u0e48\u0e2d\u0e22\u0e0a\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e08\u0e33\u0e08\u0e36\u0e07\u0e2a\u0e19\u0e43\u0e08\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01<\/span><\/p>\n\n\n<h2 class=\"has-text-color wp-block-heading\" style=\"color:#005248\"><strong>\u0e40\u0e23\u0e34\u0e48\u0e21\u0e2a\u0e2d\u0e1a\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c\u0e15\u0e2d\u0e19\u0e21.4<\/strong><\/h2>\n\n\n<p><span style=\"font-weight: 400;\">\u0e1c\u0e21\u0e44\u0e1b\u0e2a\u0e2d\u0e1a\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c\u0e04\u0e23\u0e31\u0e49\u0e07\u0e41\u0e23\u0e01\u0e15\u0e2d\u0e19\u0e21.4\u0e04\u0e23\u0e31\u0e1a \u0e15\u0e2d\u0e19\u0e19\u0e31\u0e49\u0e19\u0e1c\u0e21\u0e22\u0e31\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e19\u0e49\u0e2d\u0e22\u0e21\u0e32\u0e01\u0e46 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e0a\u0e33\u0e19\u0e32\u0e0d\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e08\u0e36\u0e07\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e15\u0e34\u0e14\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e1b\u0e34\u0e14\u0e40\u0e17\u0e2d\u0e21\u0e43\u0e2b\u0e0d\u0e48\u0e21.4 \u0e02\u0e36\u0e49\u0e19\u0e21.5 \u0e1c\u0e21\u0e08\u0e36\u0e07\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e25\u0e07<\/span><span style=\"color: #f37a01;\"><a style=\"color: #f37a01;\" href=\"https:\/\/school.dek-d.com\/course\/178\" target=\"_blank\" rel=\"noopener\"><b>\u0e04\u0e2d\u0e23\u0e4c\u0e2a\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c\u0e02\u0e2d\u0e07 Dek-D School<\/b><\/a><\/span><\/p>\n<h2 class=\"has-text-color\" style=\"color: #005248;\"><strong>\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c \u0e22\u0e31\u0e07\u0e44\u0e07\u0e43\u0e2b\u0e49\u0e15\u0e34\u0e14\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c\u0e04\u0e48\u0e32\u0e22 1 \u0e15\u0e2d\u0e19 \u0e21.5<\/strong><\/h2>\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2024\/07\/83860-768x1024.jpg\" alt=\"\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c \u0e42\u0e14\u0e22 \u0e1e\u0e35\u0e48\u0e01\u0e2d\" class=\"wp-image-91970\" width=\"384\" height=\"512\" srcset=\"https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2024\/07\/83860-768x1024.jpg 768w, https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2024\/07\/83860-225x300.jpg 225w, https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2024\/07\/83860-696x928.jpg 696w, https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2024\/07\/83860-1068x1424.jpg 1068w, https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2024\/07\/83860.jpg 1108w\" sizes=\"auto, (max-width: 384px) 100vw, 384px\" \/><\/figure><\/div>\n\n\n<p><span style=\"font-weight: 400;\">\u0e15\u0e2d\u0e19\u0e1b\u0e34\u0e14\u0e40\u0e17\u0e2d\u0e21\u0e43\u0e2b\u0e0d\u0e48\u0e21.4 \u0e02\u0e36\u0e49\u0e19\u0e21.5 \u0e1c\u0e21\u0e1e\u0e22\u0e32\u0e22\u0e32\u0e21\u0e2d\u0e48\u0e32\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e41\u0e25\u0e30\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e14\u0e49\u0e27\u0e22\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e27\u0e48\u0e32\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e2b\u0e25\u0e31\u0e01\u0e01\u0e32\u0e23\u0e21\u0e32\u0e01\u0e2a\u0e31\u0e01\u0e40\u0e17\u0e48\u0e32\u0e44\u0e23\u0e08\u0e36\u0e07\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e25\u0e07<\/span><span style=\"color: #f37a01;\"><a style=\"color: #f37a01;\" href=\"https:\/\/school.dek-d.com\/course\/178\" target=\"_blank\" rel=\"noopener\"><b>\u0e04\u0e2d\u0e23\u0e4c\u0e2a\u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c<\/b><\/a><\/span><span style=\"font-weight: 400;\"> \u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e41\u0e23\u0e01\u0e46 \u0e1c\u0e21\u0e22\u0e31\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e32\u0e21\u0e1e\u0e35\u0e48\u0e2b\u0e25\u0e34\u0e19\u0e44\u0e21\u0e48\u0e04\u0e48\u0e2d\u0e22\u0e17\u0e31\u0e19\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e04\u0e2d\u0e19\u0e40\u0e0b\u0e1b\u0e15\u0e4c\u0e01\u0e32\u0e23\u0e17\u0e33\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e02\u0e2d\u0e07\u0e1e\u0e35\u0e48\u0e40\u0e02\u0e32\u0e2a\u0e31\u0e01\u0e40\u0e17\u0e48\u0e32\u0e44\u0e2b\u0e23\u0e48\u0e41\u0e15\u0e48\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e1c\u0e21\u0e44\u0e14\u0e49\u0e25\u0e2d\u0e07\u0e17\u0e1a\u0e17\u0e27\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e46 \u0e23\u0e2d\u0e1a\u0e08\u0e32\u0e01\u0e17\u0e35\u0e48\u0e1e\u0e35\u0e48\u0e40\u0e02\u0e32\u0e2a\u0e2d\u0e19\u0e08\u0e36\u0e07\u0e40\u0e23\u0e34\u0e48\u0e21\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e02\u0e2d\u0e07\u0e1e\u0e35\u0e48\u0e2b\u0e25\u0e34\u0e19\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19\u0e41\u0e25\u0e30\u0e40\u0e23\u0e34\u0e48\u0e21\u0e17\u0e33\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e04\u0e25\u0e48\u0e2d\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e1c\u0e21\u0e01\u0e47\u0e25\u0e2d\u0e07\u0e17\u0e33\u0e01\u0e32\u0e23\u0e08\u0e31\u0e1a\u0e40\u0e27\u0e25\u0e32\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e08\u0e23\u0e34\u0e07\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e34\u0e48\u0e21\u0e04\u0e25\u0e48\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e23\u0e27\u0e14\u0e40\u0e23\u0e47\u0e27\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19\u0e08\u0e36\u0e07\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e43\u0e19\u0e2a\u0e19\u0e32\u0e21\u0e2a\u0e2d\u0e1a\u0e08\u0e23\u0e34\u0e07\u0e1c\u0e21\u0e44\u0e21\u0e48\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e15\u0e37\u0e48\u0e19\u0e40\u0e15\u0e49\u0e19\u0e40\u0e25\u0e22\u0e04\u0e23\u0e31\u0e1a \u0e0b\u0e36\u0e48\u0e07\u0e01\u0e47\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e1c\u0e21\u0e2a\u0e2d\u0e1a\u0e15\u0e34\u0e14\u0e04\u0e48\u0e32\u0e22\u0e2a\u0e2d\u0e27\u0e19.\u0e15\u0e2d\u0e19\u0e21.5 \u0e04\u0e23\u0e31\u0e1a \u0e41\u0e25\u0e30\u0e15\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e1c\u0e21\u0e2a\u0e2d\u0e1a\u0e16\u0e36\u0e07\u0e04\u0e48\u0e32\u0e222 \u0e41\u0e25\u0e49\u0e27\u0e04\u0e23\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e27\u0e25\u0e31\u0e22\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c<\/span><\/p>\n\n\n<h2 class=\"has-text-color wp-block-heading\" style=\"color:#005248\"><strong>\u0e17\u0e33\u0e44\u0e21\u0e16\u0e36\u0e07\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c\u0e01\u0e31\u0e1a\u0e2d.\u0e2b\u0e25\u0e34\u0e19 Dek-D School<\/strong><\/h2>\n\n\n<p><span style=\"color: #f37a01;\"><b>\u0e40\u0e2b\u0e15\u0e38\u0e1c\u0e25\u0e17\u0e35\u0e48\u0e1c\u0e21\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e31\u0e1a\u0e1e\u0e35\u0e48\u0e2b\u0e25\u0e34\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e23\u0e01\u0e40\u0e25\u0e22\u0e04\u0e37\u0e2d\u0e1e\u0e35\u0e48\u0e2b\u0e25\u0e34\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e14\u0e47\u0e01\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e44\u0e14\u0e49\u0e44\u0e1b\u0e15\u0e48\u0e2d\u0e16\u0e36\u0e07\u0e42\u0e2d\u0e25\u0e34\u0e21\u0e1b\u0e34\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e19\u0e32\u0e19\u0e32\u0e0a\u0e32\u0e15\u0e34\u0e14\u0e49\u0e27\u0e22<\/b><\/span><span style=\"font-weight: 400;\">\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e1c\u0e21\u0e04\u0e34\u0e14\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e31\u0e1a\u0e04\u0e19\u0e17\u0e35\u0e48\u0e40\u0e04\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e17\u0e33\u0e02\u0e49\u0e2d\u0e2a\u0e2d\u0e1a\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e19\u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e23\u0e39\u0e49\u0e17\u0e23\u0e34\u0e04\u0e41\u0e25\u0e30\u0e27\u0e34\u0e18\u0e35\u0e17\u0e33\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07<\/span><span style=\"color: #f37a01;\"><b> \u0e2a\u0e48\u0e27\u0e19\u0e40\u0e2b\u0e15\u0e38\u0e1c\u0e25\u0e15\u0e48\u0e2d\u0e21\u0e32\u0e04\u0e37\u0e2d\u0e23\u0e32\u0e04\u0e32\u0e04\u0e23\u0e31\u0e1a\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e04\u0e2d\u0e23\u0e4c\u0e2a\u0e19\u0e35\u0e49\u0e21\u0e35\u0e23\u0e32\u0e04\u0e32\u0e17\u0e35\u0e48\u0e04\u0e38\u0e49\u0e21\u0e21\u0e32\u0e01<\/b><\/span><span style=\"font-weight: 400;\">\u0e04\u0e23\u0e31\u0e1a\u0e41\u0e25\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e1c\u0e21\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e07\u0e1a\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e20\u0e32\u0e22\u0e43\u0e19\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22 <\/span><\/p>\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>\u201c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e2b\u0e25\u0e31\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1c\u0e21\u0e1a\u0e2d\u0e01\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22\u0e27\u0e48\u0e32\u0e1e\u0e35\u0e48\u0e2b\u0e25\u0e34\u0e19\u0e40\u0e1b\u0e23\u0e35\u0e22\u0e1a\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e38\u0e0d\u0e41\u0e08\u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1b\u0e25\u0e14\u0e25\u0e47\u0e2d\u0e04\u0e04\u0e27\u0e32\u0e21\u0e01\u0e31\u0e07\u0e27\u0e25\u0e02\u0e2d\u0e07\u0e1c\u0e21\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e02\u0e49\u0e2d\u0e2a\u0e2d\u0e1a\u0e1c\u0e21\u0e44\u0e14\u0e49\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e01\u0e32\u0e23\u0e15\u0e35\u0e42\u0e08\u0e17\u0e22\u0e4c \u0e01\u0e32\u0e23\u0e17\u0e33\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e47\u0e27\u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e40\u0e2a\u0e35\u0e22\u0e40\u0e27\u0e25\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e17\u0e23\u0e34\u0e04\u0e01\u0e32\u0e23\u0e17\u0e33\u0e02\u0e49\u0e2d\u0e40\u0e02\u0e35\u0e22\u0e19\u0e14\u0e49\u0e27\u0e22\u0e04\u0e23\u0e31\u0e1a\u201d<\/strong><\/p><\/blockquote>\n\n\n\n<h2 class=\"has-text-color wp-block-heading\" style=\"color:#005248\"><strong>\u0e44\u0e14\u0e49\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e2d\u0e30\u0e44\u0e23\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e2a\u0e2d\u0e27\u0e19.\u0e1a\u0e49\u0e32\u0e07?<\/strong><\/h2>\n\n\n<p><span style=\"font-weight: 400;\">\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e04\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e15\u0e47\u0e21\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e40\u0e04\u0e22\u0e17\u0e33\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e19\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e23\u0e32\u0e44\u0e14\u0e49\u0e1d\u0e36\u0e01\u0e1d\u0e19\u0e21\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e15\u0e47\u0e21\u0e17\u0e35\u0e48 \u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e19\u0e2d\u0e01\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e08\u0e32\u0e01\u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e17\u0e33\u0e02\u0e49\u0e2d\u0e2a\u0e2d\u0e1a\u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e02\u0e2d\u0e07\u0e02\u0e49\u0e2d\u0e40\u0e02\u0e35\u0e22\u0e19\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e01\u0e32\u0e23\u0e04\u0e34\u0e14\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e35\u0e25\u0e33\u0e14\u0e31\u0e1a\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e21\u0e35\u0e40\u0e2b\u0e15\u0e38\u0e1c\u0e25 \u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e43\u0e0a\u0e49\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e19\u0e33\u0e44\u0e1b\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e48\u0e2d\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e44\u0e14\u0e49\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e2b\u0e32\u0e25\u0e31\u0e22\u0e02\u0e49\u0e2d\u0e2a\u0e2d\u0e1a\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e49\u0e2d\u0e40\u0e02\u0e35\u0e22\u0e19<\/span><\/p>\n\n\n<h2 class=\"has-text-color wp-block-heading\" style=\"color:#005248\"><strong>\u0e2d\u0e22\u0e32\u0e01\u0e43\u0e2b\u0e49\u0e41\u0e0a\u0e23\u0e4c\u0e40\u0e04\u0e25\u0e47\u0e14\u0e25\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e43\u0e2b\u0e49\u0e15\u0e34\u0e14\u0e04\u0e48\u0e32\u0e22\u0e2a\u0e2d\u0e27\u0e19.\u0e2b\u0e19\u0e48\u0e2d\u0e22\u0e04\u0e48\u0e30<\/strong><\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2024\/07\/83868.jpg\" alt=\"\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c \u0e42\u0e14\u0e22 \u0e1e\u0e35\u0e48\u0e01\u0e2d\u0e25\u0e4c\u0e1f\n\" class=\"wp-image-91973\" width=\"304\" height=\"335\" srcset=\"https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2024\/07\/83868.jpg 607w, https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2024\/07\/83868-272x300.jpg 272w\" sizes=\"auto, (max-width: 304px) 100vw, 304px\" \/><\/figure><\/div>\n\n\n<p><span style=\"font-weight: 400;\">\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e21<\/span><b><span style=\"color: #f37a01;\">\u0e40\u0e04\u0e25\u0e47\u0e14\u0e25\u0e31\u0e1a\u0e04\u0e37\u0e2d\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e08\u0e32\u0e01\u0e42\u0e08\u0e17\u0e22\u0e4c<\/span>\u0e40<\/b><span style=\"font-weight: 400;\">\u0e1e\u0e23\u0e32\u0e30\u0e01\u0e32\u0e23\u0e2d\u0e48\u0e32\u0e19\u0e41\u0e15\u0e48\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e41\u0e15\u0e48\u0e44\u0e21\u0e48\u0e17\u0e33\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e01\u0e47\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e39\u0e49\u0e41\u0e15\u0e48\u0e17\u0e24\u0e29\u0e0e\u0e35\u0e41\u0e15\u0e48\u0e44\u0e21\u0e48\u0e25\u0e07\u0e21\u0e37\u0e2d\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e09\u0e30\u0e19\u0e31\u0e49\u0e19\u0e2b\u0e32\u0e01\u0e2d\u0e22\u0e32\u0e01\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14\u0e02\u0e2d\u0e07\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e17\u0e33\u0e40\u0e25\u0e22\u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e17\u0e33\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e19\u0e33\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e09\u0e25\u0e22\u0e41\u0e25\u0e49\u0e27\u0e21\u0e32\u0e2d\u0e48\u0e32\u0e19\u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e41\u0e01\u0e49\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19\u0e41\u0e25\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e44\u0e21\u0e48\u0e15\u0e34\u0e14\u0e02\u0e31\u0e14\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e33\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e2d\u0e35\u0e01\u0e40\u0e25\u0e22<\/span><\/p>\n<h2 class=\"has-text-color\" style=\"color: #005248;\"><strong>\u0e17\u0e33\u0e44\u0e21\u0e16\u0e36\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e2a\u0e2d\u0e27\u0e19.\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e21\u0e35\u0e02\u0e49\u0e2d\u0e14\u0e35\u0e15\u0e23\u0e07\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e23\u0e35\u0e22\u0e19\u0e40\u0e27\u0e25\u0e32\u0e44\u0e2b\u0e19\u0e01\u0e47\u0e44\u0e14\u0e49\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e48\u0e32\u0e07\u0e41\u0e25\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e23\u0e35\u0e22\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e44\u0e21\u0e48\u0e15\u0e34\u0e14\u0e02\u0e31\u0e14\u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e14\u0e39\u0e22\u0e49\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e44\u0e14\u0e49 \u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e02\u0e2d\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e04\u0e37\u0e2d\u0e22\u0e31\u0e07\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e40\u0e1a\u0e37\u0e48\u0e2d\u0e46 \u0e1a\u0e49\u0e32\u0e07\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e1a\u0e32\u0e07\u0e17\u0e35\u0e2d\u0e32\u0e08\u0e2a\u0e21\u0e32\u0e18\u0e34\u0e2b\u0e25\u0e38\u0e14\u0e44\u0e1b\u0e17\u0e33\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1a\u0e49\u0e32\u0e07 \u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e19\u0e35\u0e49\u0e1c\u0e21\u0e41\u0e01\u0e49\u0e44\u0e02\u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e44\u0e21\u0e48\u0e2d\u0e48\u0e32\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e40\u0e22\u0e2d\u0e30\u0e41\u0e15\u0e48\u0e40\u0e19\u0e49\u0e19\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e17\u0e33\u0e02\u0e49\u0e2d\u0e2a\u0e2d\u0e1a\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e01\u0e32\u0e23\u0e17\u0e33\u0e02\u0e49\u0e2d\u0e2a\u0e2d\u0e1a\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e1c\u0e21\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e15\u0e37\u0e48\u0e19\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e21\u0e32\u0e18\u0e34\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e39\u0e07\u0e41\u0e25\u0e30\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e32\u0e17\u0e33\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e2a\u0e19\u0e38\u0e01\u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e07\u0e48\u0e27\u0e07\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22<\/span><\/p>\n\n\n<h2 class=\"has-text-color wp-block-heading\" style=\"color:#005248\"><strong>\u0e19\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e08\u0e32\u0e01\u0e04\u0e48\u0e32\u0e22\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e48\u0e2d\u0e43\u0e19\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22<\/strong><\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2024\/07\/83861-1024x683.jpg\" alt=\" \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c \u0e42\u0e14\u0e22 \u0e1e\u0e35\u0e48\u0e01\u0e2d\u0e25\u0e4c\u0e1f\" class=\"wp-image-91975\" width=\"512\" height=\"342\" srcset=\"https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2024\/07\/83861-1024x683.jpg 1024w, https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2024\/07\/83861-300x200.jpg 300w, https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2024\/07\/83861-768x512.jpg 768w, https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2024\/07\/83861-696x464.jpg 696w, https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2024\/07\/83861-1068x712.jpg 1068w, https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2024\/07\/83861.jpg 1080w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/figure><\/div>\n\n\n<p><span style=\"font-weight: 400;\">\u0e15\u0e48\u0e2d\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e1c\u0e21\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e2a\u0e32\u0e02\u0e32\u0e19\u0e35\u0e49\u0e43\u0e0a\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e43\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e23\u0e35\u0e22\u0e19\u0e21\u0e32\u0e43\u0e19\u0e04\u0e48\u0e32\u0e22\u0e08\u0e36\u0e07\u0e04\u0e34\u0e14\u0e27\u0e48\u0e32\u0e16\u0e19\u0e31\u0e14\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e15\u0e19\u0e40\u0e2d\u0e07 \u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e35\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e44\u0e1b\u0e25\u0e38\u0e22\u0e2a\u0e2d\u0e27\u0e19.\u0e2d\u0e30\u0e44\u0e23\u0e15\u0e48\u0e2d\u0e44\u0e2b\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e35\u0e49\u0e1c\u0e21\u0e04\u0e34\u0e14\u0e27\u0e48\u0e32\u0e04\u0e07\u0e44\u0e21\u0e48\u0e2a\u0e2d\u0e1a\u0e2d\u0e30\u0e44\u0e23\u0e15\u0e48\u0e2d\u0e41\u0e25\u0e49\u0e27\u0e08\u0e30\u0e40\u0e19\u0e49\u0e19\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e15\u0e31\u0e27\u0e40\u0e02\u0e49\u0e32\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27\u0e40\u0e25\u0e22\u0e14\u0e35\u0e01\u0e27\u0e48\u0e32\u0e04\u0e23\u0e31\u0e1a<\/span><\/p>\n\n\n<h2 class=\"has-text-color wp-block-heading\" style=\"color:#005248\"><strong>\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22\u0e19\u0e35\u0e49\u0e2d\u0e22\u0e32\u0e01\u0e43\u0e2b\u0e49\u0e1d\u0e32\u0e01\u0e16\u0e36\u0e07\u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e2d\u0e22\u0e32\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e14\u0e47\u0e01\u0e04\u0e48\u0e32\u0e22\u0e2b\u0e19\u0e48\u0e2d\u0e22\u0e04\u0e48\u0e30<\/strong><\/h2>\n\n\n<p><span style=\"font-weight: 400;\">\u0e2a\u0e34\u0e48\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27\u0e17\u0e35\u0e48\u0e1c\u0e21\u0e2d\u0e22\u0e32\u0e01\u0e1d\u0e32\u0e01\u0e23\u0e38\u0e48\u0e19\u0e19\u0e49\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e32\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e14\u0e47\u0e01\u0e04\u0e48\u0e32\u0e22\u0e04\u0e37\u0e2d \u0e16\u0e49\u0e32\u0e22\u0e31\u0e07\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e40\u0e04\u0e23\u0e35\u0e22\u0e14\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e44\u0e21\u0e48\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e31\u0e07\u0e17\u0e33\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e44\u0e21\u0e48\u0e2d\u0e2d\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e40\u0e1e\u0e34\u0e48\u0e07\u0e17\u0e49\u0e2d\u0e43\u0e2b\u0e49\u0e25\u0e2d\u0e07\u0e2b\u0e22\u0e38\u0e14\u0e17\u0e33\u0e41\u0e25\u0e49\u0e27\u0e25\u0e2d\u0e07\u0e19\u0e31\u0e48\u0e07\u0e2a\u0e21\u0e32\u0e18\u0e34\u0e04\u0e34\u0e14\u0e17\u0e1a\u0e17\u0e27\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e1b\u0e23\u0e30\u0e21\u0e32\u0e1310\u0e19\u0e32\u0e17\u0e35 \u0e19\u0e35\u0e48\u0e04\u0e37\u0e2d\u0e17\u0e23\u0e34\u0e04\u0e17\u0e35\u0e48\u0e1c\u0e21\u0e17\u0e33\u0e0b\u0e36\u0e48\u0e07\u0e21\u0e31\u0e19\u0e08\u0e30\u0e0a\u0e49\u0e27\u0e22\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e21\u0e35\u0e2a\u0e21\u0e32\u0e18\u0e34\u0e41\u0e25\u0e30\u0e08\u0e33\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33\u0e41\u0e25\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e34\u0e48\u0e21\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e27\u0e48\u0e32\u0e17\u0e33\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e44\u0e14\u0e49\u0e41\u0e25\u0e49\u0e27\u0e01\u0e47\u0e43\u0e2b\u0e49\u0e17\u0e33\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e43\u0e2b\u0e49\u0e02\u0e32\u0e14\u0e15\u0e2d\u0e19\u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e0a\u0e33\u0e19\u0e32\u0e0d\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e02\u0e49\u0e2d\u0e2a\u0e2d\u0e1a\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22\u0e1c\u0e21\u0e2d\u0e22\u0e32\u0e01\u0e1d\u0e32\u0e01\u0e04\u0e33\u0e04\u0e21\u0e43\u0e2b\u0e49\u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e2a\u0e31\u0e01\u0e40\u0e25\u0e47\u0e01\u0e46 \u0e27\u0e48\u0e32<\/span><b>&nbsp;<\/b><\/p>\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>\u201c\u0e08\u0e07\u0e27\u0e34\u0e48\u0e07 \u0e16\u0e49\u0e32\u0e27\u0e34\u0e48\u0e07\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e08\u0e07\u0e40\u0e14\u0e34\u0e19 \u0e16\u0e49\u0e32\u0e40\u0e14\u0e34\u0e19\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e08\u0e07\u0e04\u0e25\u0e32\u0e19 \u0e17\u0e33\u0e22\u0e31\u0e07\u0e44\u0e07\u0e01\u0e47\u0e44\u0e14\u0e49\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e44\u0e1b\u0e02\u0e49\u0e32\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e21\u0e49\u0e08\u0e30\u0e0a\u0e49\u0e32\u0e22\u0e31\u0e07\u0e44\u0e07\u0e01\u0e47\u0e15\u0e32\u0e21\u0e02\u0e2d\u0e41\u0e04\u0e48\u0e2d\u0e22\u0e48\u0e32\u0e43\u0e2b\u0e49\u0e21\u0e31\u0e19\u0e2b\u0e22\u0e38\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e17\u0e35\u0e48\u201d<\/strong><\/p><\/blockquote>\n\n\n<p><span style=\"font-weight: 400;\">\u0e41\u0e21\u0e49\u0e15\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e08\u0e30\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e40\u0e27\u0e25\u0e32\u0e44\u0e21\u0e48\u0e21\u0e32\u0e01\u0e41\u0e25\u0e49\u0e27\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e15\u0e31\u0e27\u0e2a\u0e2d\u0e1a\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e49\u0e32\u0e27\u0e44\u0e1b\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e14\u0e47\u0e01\u0e04\u0e48\u0e32\u0e22\u0e2a\u0e2d\u0e27\u0e19. \u0e41\u0e15\u0e48\u0e2b\u0e32\u0e01\u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e15\u0e31\u0e27\u0e43\u0e2b\u0e49\u0e1e\u0e23\u0e49\u0e2d\u0e21 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e15\u0e47\u0e21\u0e17\u0e35\u0e48 \u0e1e\u0e35\u0e48\u0e27\u0e48\u0e32\u0e17\u0e38\u0e01\u0e04\u0e19\u0e01\u0e47\u0e21\u0e35\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e01\u0e49\u0e32\u0e27\u0e44\u0e1b\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e14\u0e47\u0e01\u0e04\u0e48\u0e32\u0e22\u0e44\u0e14\u0e49 \u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e32\u0e01\u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e2d\u0e22\u0e32\u0e01\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c \u0e01\u0e48\u0e2d\u0e19\u0e2a\u0e2d\u0e1a\u0e21\u0e32\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e08\u0e32\u0e01\u0e1e\u0e35\u0e48\u0e01\u0e2d\u0e25\u0e4c\u0e1f\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22\u0e04\u0e48\u0e30<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u0e41\u0e25\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e2d\u0e22\u0e32\u0e01\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e2a\u0e2d\u0e27\u0e19.\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e1a\u0e1e\u0e35\u0e48\u0e01\u0e2d\u0e25\u0e4c\u0e1f \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16<\/span><span style=\"color: #f37a01;\"><a style=\"color: #f37a01;\" href=\"https:\/\/school.dek-d.com\/course\/178\" target=\"_blank\" rel=\"noopener\"><b>\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e15\u0e31\u0e27\u0e2a\u0e2d\u0e1a\u0e2a\u0e2d\u0e27\u0e19. \u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c<\/b><\/a><\/span><span style=\"font-weight: 400;\">\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e32\u0e23<\/span><span style=\"color: #f37a01;\"><a style=\"color: #f37a01;\" href=\"https:\/\/school.dek-d.com\/\" target=\"_blank\" rel=\"noopener\"><b>\u0e15\u0e34\u0e27\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e01\u0e31\u0e1a Dek-D School <\/b><\/a><\/span><span style=\"font-weight: 400;\">\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22\u0e04\u0e48\u0e30 \u0e0b\u0e36\u0e48\u0e07\u0e04\u0e2d\u0e23\u0e4c\u0e2a\u0e19\u0e35\u0e49\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e42\u0e14\u0e22\u0e2d.\u0e2b\u0e25\u0e34\u0e19 (\u0e1c\u0e28.\u0e14\u0e23. \u0e2a\u0e25\u0e34\u0e25\u0e1e\u0e23 \u0e01\u0e34\u0e15\u0e15\u0e34\u0e27\u0e31\u0e12\u0e19\u0e32\u0e01\u0e39\u0e25) \u0e1c\u0e39\u0e49\u0e2b\u0e0d\u0e34\u0e07\u0e44\u0e17\u0e22\u0e04\u0e19\u0e41\u0e23\u0e01\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e43\u0e19\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c\u0e42\u0e2d\u0e25\u0e34\u0e21\u0e1b\u0e34\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e19\u0e32\u0e19\u0e32\u0e0a\u0e32\u0e15\u0e34 \u0e41\u0e25\u0e30\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e20\u0e32\u0e04\u0e27\u0e34\u0e0a\u0e32\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c \u0e04\u0e13\u0e30\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e08\u0e38\u0e2c\u0e32\u0e25\u0e07\u0e01\u0e23\u0e13\u0e4c\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e42\u0e14\u0e22\u0e04\u0e2d\u0e23\u0e4c\u0e2a\u0e19\u0e35\u0e49\u0e08\u0e30\u0e1b\u0e34\u0e14\u0e08\u0e38\u0e14\u0e2d\u0e48\u0e2d\u0e19 \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e08\u0e38\u0e14\u0e41\u0e02\u0e47\u0e07\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32 \u0e17\u0e35\u0e48\u0e21\u0e32\u0e02\u0e2d\u0e07\u0e2a\u0e39\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e19\u0e33\u0e21\u0e32\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e0b\u0e36\u0e48\u0e07\u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e1a\u0e17\u0e27\u0e19\u0e0b\u0e49\u0e33\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e08\u0e33\u0e01\u0e31\u0e14\u0e16\u0e36\u0e07 1 \u0e1b\u0e35&nbsp; \u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e41\u0e21\u0e49\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e15\u0e48\u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e17\u0e38\u0e01\u0e04\u0e19\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e2d\u0e1a\u0e16\u0e32\u0e21\u0e02\u0e49\u0e2d\u0e2a\u0e07\u0e2a\u0e31\u0e22\u0e01\u0e31\u0e1a\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e1c\u0e39\u0e49\u0e2a\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e41\u0e08\u0e49\u0e07\u0e40\u0e15\u0e37\u0e2d\u0e19\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e21\u0e35\u0e01\u0e32\u0e23\u0e15\u0e2d\u0e1a\u0e01\u0e25\u0e31\u0e1a \u0e16\u0e49\u0e32\u0e44\u0e21\u0e48\u0e2d\u0e22\u0e32\u0e01\u0e1e\u0e25\u0e32\u0e14\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e14\u0e35\u0e46 \u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49 \u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e44\u0e14\u0e49\u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e04\u0e25\u0e34\u0e01\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e17\u0e35\u0e48\u0e23\u0e39\u0e1b\u0e14\u0e49\u0e32\u0e19\u0e25\u0e48\u0e32\u0e07\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22\u0e04\u0e48\u0e30<\/span><\/p>\n\n\n<iframe class=\"course-item-embed\" src=\"https:\/\/school.dek-d.com\/embed\/course\/178\" style=\"display:block; margin: 20px auto 30px; width: 100%; border:none; overflow:hidden; min-height: 160px;\"><\/iframe>\n\n\n\n<iframe class=\"course-item-embed\" src=\"https:\/\/school.dek-d.com\/embed\/course\/189\" style=\"display:block; margin: 20px auto 30px; width: 100%; border:none; overflow:hidden; min-height: 160px;\"><\/iframe>\n\n\n<p><span style=\"font-weight: 400;\">\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e22\u0e31\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e2a\u0e32\u0e23\u0e30\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a \u0e2a\u0e2d\u0e27\u0e19.\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48&nbsp; <\/span><span style=\"color: #f37a01;\"><a style=\"color: #f37a01;\" href=\"https:\/\/www.facebook.com\/schooldekd\"><b>Facebook : Dek-D School : \u0e04\u0e2d\u0e23\u0e4c\u0e2a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e17\u0e35\u0e48\u0e40\u0e23\u0e35\u0e22\u0e19\u0e44\u0e14\u0e49\u0e17\u0e38\u0e01\u0e04\u0e19 <\/b><\/a><\/span><span style=\"font-weight: 400;\">\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e2a\u0e2d\u0e27\u0e19.\u0e01\u0e31\u0e1a \u0e1e\u0e35\u0e48\u0e46 <\/span><span style=\"color: #f37a01;\"><a style=\"color: #f37a01;\" href=\"https:\/\/school.dek-d.com\/\" target=\"_blank\" rel=\"noopener\"><b>Dek-D School<\/b><\/a><\/span><span style=\"font-weight: 400;\"> \u0e44\u0e14\u0e49\u0e1f\u0e23\u0e35!!!\u0e17\u0e35\u0e48 Line <\/span><span style=\"color: #f37a01;\"><a style=\"color: #f37a01;\" href=\"https:\/\/page.line.me\/quh3207q?openQrModal=true\" target=\"_blank\" rel=\"noopener\"><b>@schooldekd<\/b><\/a><\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e2d\u0e22\u0e32\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e14\u0e47\u0e01\u0e04\u0e48\u0e32\u0e22\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e15\u0e48\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e23\u0e39\u0e49\u0e08\u0e30\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e15\u0e31\u0e27\u0e22\u0e31\u0e07\u0e44\u0e07\u0e43\u0e2b\u0e49\u0e15\u0e34\u0e14\u0e04\u0e48\u0e32\u0e22\u0e14\u0e35 \u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e42\u0e04\u0e49\u0e07\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22\u0e01\u0e48\u0e2d\u0e19\u0e2a\u0e2d\u0e1a\u0e19\u0e35\u0e49 \u0e21\u0e32\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c \u0e14\u0e48\u0e27\u0e19\u0e46 \u0e08\u0e32\u0e01\u0e1e\u0e35\u0e48\u0e01\u0e2d\u0e25\u0e4c\u0e1f\u0e23\u0e38\u0e48\u0e19\u0e1e\u0e35\u0e48\u0e40\u0e14\u0e47\u0e01\u0e04\u0e48\u0e32\u0e22\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22 \u0e1e\u0e35\u0e48\u0e01\u0e2d\u0e25\u0e4c\u0e1f\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e15\u0e31\u0e27\u0e2a\u0e2d\u0e1a \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23 \u0e15\u0e34\u0e27\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e04\u0e2d\u0e23\u0e4c\u0e2a\u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c\u0e01\u0e31\u0e1a\u0e2d.\u0e2b\u0e25\u0e34\u0e19 Dek-D School \u0e08\u0e19\u0e2a\u0e2d\u0e1a\u0e15\u0e34\u0e14\u0e04\u0e48\u0e32\u0e22 2 \u0e16\u0e49\u0e32\u0e2d\u0e22\u0e32\u0e01\u0e23\u0e39\u0e49\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e41\u0e25\u0e49\u0e27 \u0e44\u0e1b\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22 \u0e01\u0e48\u0e2d\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e2b\u0e49\u0e19\u0e49\u0e2d\u0e07\u0e41\u0e19\u0e30\u0e19\u0e33\u0e15\u0e31\u0e27\u0e01\u0e48\u0e2d\u0e19\u0e04\u0e48\u0e30 \u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e35\u0e04\u0e23\u0e31\u0e1a\u0e1c\u0e21 \u0e01\u0e24\u0e15\u0e40\u0e21\u0e18 \u0e07\u0e32\u0e21\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e25\u0e48\u0e19 \u0e01\u0e2d\u0e25\u0e4c\u0e1f \u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e0a\u0e31\u0e49\u0e19\u0e21.6 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e17\u0e38\u0e48\u0e07\u0e2a\u0e07 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u0e2d\u0e22\u0e32\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e14\u0e47\u0e01\u0e04\u0e48\u0e32\u0e22\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e41\u0e25\u0e30\u0e44\u0e14\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e21\u0e35\u0e2a\u0e2d\u0e19\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e1c\u0e21\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e27\u0e19.\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e2d\u0e01\u0e40\u0e25\u0e48\u0e32\u0e02\u0e2d\u0e07\u0e04\u0e23\u0e39\u0e43\u0e19\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e2d\u0e19\u0e21.4 \u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e2a\u0e2d\u0e27\u0e19.\u0e21\u0e35\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e1a\u0e31\u0e15\u0e23\u0e17\u0e35\u0e48\u0e21\u0e35\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e21\u0e2b\u0e32\u0e25\u0e31\u0e22\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e1c\u0e21\u0e08\u0e36\u0e07\u0e2a\u0e19\u0e43\u0e08\u0e17\u0e35\u0e48\u0e08\u0e30\u0e2a\u0e2d\u0e1a\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e02\u0e2d\u0e07\u0e15\u0e19\u0e40\u0e2d\u0e07 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e1c\u0e21\u0e22\u0e31\u0e07\u0e2d\u0e22\u0e32\u0e01\u0e17\u0e35\u0e48\u0e08\u0e30\u0e44\u0e14\u0e49\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e40\u0e02\u0e49\u0e32\u0e04\u0e48\u0e32\u0e22\u0e2a\u0e2d\u0e27\u0e19.\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e43\u0e19\u0e04\u0e48\u0e32\u0e22\u0e08\u0e30\u0e2d\u0e1a\u0e23\u0e21\u0e43\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e21\u0e35\u0e43\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e1b\u0e01\u0e15\u0e34\u0e17\u0e31\u0e49\u0e07\u0e22\u0e31\u0e07\u0e44\u0e14\u0e49\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e01\u0e31\u0e1a\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e15\u0e48\u0e32\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e0b\u0e36\u0e48\u0e07\u0e01\u0e34\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e2b\u0e25\u0e31\u0e1a\u0e19\u0e2d\u0e19\u0e14\u0e49\u0e27\u0e22\u0e01\u0e31\u0e19\u0e43\u0e19\u0e04\u0e48\u0e32\u0e22 \u0e17\u0e33\u0e44\u0e21\u0e16\u0e36\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2a\u0e2d\u0e1a\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c? \u0e1c\u0e21\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e2d\u0e1a\u0e40\u0e40\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e43\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e38\u0e19\u0e40\u0e14\u0e34\u0e21\u0e2d\u0e22\u0e39\u0e48\u0e40\u0e40\u0e25\u0e49\u0e27\u0e08\u0e36\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e27\u0e34\u0e0a\u0e32\u0e19\u0e35\u0e49\u0e41\u0e25\u0e30\u0e27\u0e34\u0e0a\u0e32\u0e19\u0e35\u0e49\u0e01\u0e47\u0e40\u0e19\u0e49\u0e19\u0e01\u0e32\u0e23\u0e04\u0e33\u0e19\u0e27\u0e13\u0e40\u0e40\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e43\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e01\u0e32\u0e23\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e08\u0e33\u0e1c\u0e21\u0e17\u0e35\u0e48\u0e16\u0e19\u0e31\u0e14\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e04\u0e33\u0e19\u0e27\u0e13\u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e04\u0e48\u0e2d\u0e22\u0e0a\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e08\u0e33\u0e08\u0e36\u0e07\u0e2a\u0e19\u0e43\u0e08\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01 \u0e40\u0e23\u0e34\u0e48\u0e21\u0e2a\u0e2d\u0e1a\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c\u0e15\u0e2d\u0e19\u0e21.4 \u0e1c\u0e21\u0e44\u0e1b\u0e2a\u0e2d\u0e1a\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c\u0e04\u0e23\u0e31\u0e49\u0e07\u0e41\u0e23\u0e01\u0e15\u0e2d\u0e19\u0e21.4\u0e04\u0e23\u0e31\u0e1a \u0e15\u0e2d\u0e19\u0e19\u0e31\u0e49\u0e19\u0e1c\u0e21\u0e22\u0e31\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e19\u0e49\u0e2d\u0e22\u0e21\u0e32\u0e01\u0e46 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e0a\u0e33\u0e19\u0e32\u0e0d\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e08\u0e36\u0e07\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e15\u0e34\u0e14\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e1b\u0e34\u0e14\u0e40\u0e17\u0e2d\u0e21\u0e43\u0e2b\u0e0d\u0e48\u0e21.4 \u0e02\u0e36\u0e49\u0e19\u0e21.5 \u0e1c\u0e21\u0e08\u0e36\u0e07\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e25\u0e07\u0e04\u0e2d\u0e23\u0e4c\u0e2a\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c\u0e02\u0e2d\u0e07 Dek-D School \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c \u0e22\u0e31\u0e07\u0e44\u0e07\u0e43\u0e2b\u0e49\u0e15\u0e34\u0e14\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c\u0e04\u0e48\u0e32\u0e22 1 \u0e15\u0e2d\u0e19 \u0e21.5 \u0e15\u0e2d\u0e19\u0e1b\u0e34\u0e14\u0e40\u0e17\u0e2d\u0e21\u0e43\u0e2b\u0e0d\u0e48\u0e21.4 \u0e02\u0e36\u0e49\u0e19\u0e21.5 \u0e1c\u0e21\u0e1e\u0e22\u0e32\u0e22\u0e32\u0e21\u0e2d\u0e48\u0e32\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e41\u0e25\u0e30\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e14\u0e49\u0e27\u0e22\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e27\u0e48\u0e32\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e2b\u0e25\u0e31\u0e01\u0e01\u0e32\u0e23\u0e21\u0e32\u0e01\u0e2a\u0e31\u0e01\u0e40\u0e17\u0e48\u0e32\u0e44\u0e23\u0e08\u0e36\u0e07\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e25\u0e07\u0e04\u0e2d\u0e23\u0e4c\u0e2a\u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c \u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e41\u0e23\u0e01\u0e46 \u0e1c\u0e21\u0e22\u0e31\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e32\u0e21\u0e1e\u0e35\u0e48\u0e2b\u0e25\u0e34\u0e19\u0e44\u0e21\u0e48\u0e04\u0e48\u0e2d\u0e22\u0e17\u0e31\u0e19\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e04\u0e2d\u0e19\u0e40\u0e0b\u0e1b\u0e15\u0e4c\u0e01\u0e32\u0e23\u0e17\u0e33\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e02\u0e2d\u0e07\u0e1e\u0e35\u0e48\u0e40\u0e02\u0e32\u0e2a\u0e31\u0e01\u0e40\u0e17\u0e48\u0e32\u0e44\u0e2b\u0e23\u0e48\u0e41\u0e15\u0e48\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e1c\u0e21\u0e44\u0e14\u0e49\u0e25\u0e2d\u0e07\u0e17\u0e1a\u0e17\u0e27\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e46 \u0e23\u0e2d\u0e1a\u0e08\u0e32\u0e01\u0e17\u0e35\u0e48\u0e1e\u0e35\u0e48\u0e40\u0e02\u0e32\u0e2a\u0e2d\u0e19\u0e08\u0e36\u0e07\u0e40\u0e23\u0e34\u0e48\u0e21\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e02\u0e2d\u0e07\u0e1e\u0e35\u0e48\u0e2b\u0e25\u0e34\u0e19\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19\u0e41\u0e25\u0e30\u0e40\u0e23\u0e34\u0e48\u0e21\u0e17\u0e33\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e04\u0e25\u0e48\u0e2d\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e1c\u0e21\u0e01\u0e47\u0e25\u0e2d\u0e07\u0e17\u0e33\u0e01\u0e32\u0e23\u0e08\u0e31\u0e1a\u0e40\u0e27\u0e25\u0e32\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e08\u0e23\u0e34\u0e07\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e34\u0e48\u0e21\u0e04\u0e25\u0e48\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e23\u0e27\u0e14\u0e40\u0e23\u0e47\u0e27\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19\u0e08\u0e36\u0e07\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e43\u0e19\u0e2a\u0e19\u0e32\u0e21\u0e2a\u0e2d\u0e1a\u0e08\u0e23\u0e34\u0e07\u0e1c\u0e21\u0e44\u0e21\u0e48\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e15\u0e37\u0e48\u0e19\u0e40\u0e15\u0e49\u0e19\u0e40\u0e25\u0e22\u0e04\u0e23\u0e31\u0e1a \u0e0b\u0e36\u0e48\u0e07\u0e01\u0e47\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e1c\u0e21\u0e2a\u0e2d\u0e1a\u0e15\u0e34\u0e14\u0e04\u0e48\u0e32\u0e22\u0e2a\u0e2d\u0e27\u0e19.\u0e15\u0e2d\u0e19\u0e21.5 \u0e04\u0e23\u0e31\u0e1a \u0e41\u0e25\u0e30\u0e15\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e1c\u0e21\u0e2a\u0e2d\u0e1a\u0e16\u0e36\u0e07\u0e04\u0e48\u0e32\u0e222 [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":91979,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[11,252,100],"tags":[394,442,525,205,140,506,440,509],"class_list":{"0":"post-91967","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-featured","8":"category-review","9":"category-recommend","10":"tag-dekdschool-2","11":"tag-442","12":"tag-525","13":"tag-205","14":"tag-140","15":"tag-506","16":"tag-440","17":"tag-509"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e41\u0e0a\u0e23\u0e4c\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c \u0e15\u0e34\u0e14\u0e04\u0e48\u0e32\u0e22 2 \u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c<\/title>\n<meta name=\"description\" content=\"\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c \u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e42\u0e04\u0e49\u0e07\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22 \u0e21\u0e32\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e14\u0e48\u0e27\u0e19\u0e46 \u0e08\u0e32\u0e01\u0e1e\u0e35\u0e48\u0e01\u0e2d\u0e25\u0e4c\u0e1f\u0e23\u0e38\u0e48\u0e19\u0e1e\u0e35\u0e48\u0e40\u0e14\u0e47\u0e01\u0e04\u0e48\u0e32\u0e22\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/school.dek-d.com\/blog\/review\/posn-physics-golf\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e41\u0e0a\u0e23\u0e4c\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c \u0e15\u0e34\u0e14\u0e04\u0e48\u0e32\u0e22 2 \u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\" \/>\n<meta property=\"og:description\" content=\"\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c \u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e42\u0e04\u0e49\u0e07\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22 \u0e21\u0e32\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e14\u0e48\u0e27\u0e19\u0e46 \u0e08\u0e32\u0e01\u0e1e\u0e35\u0e48\u0e01\u0e2d\u0e25\u0e4c\u0e1f\u0e23\u0e38\u0e48\u0e19\u0e1e\u0e35\u0e48\u0e40\u0e14\u0e47\u0e01\u0e04\u0e48\u0e32\u0e22\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22\" \/>\n<meta property=\"og:url\" content=\"https:\/\/school.dek-d.com\/blog\/review\/posn-physics-golf\/\" \/>\n<meta property=\"og:site_name\" content=\"Dek-D&#039;s School\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kidcoding\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-25T06:46:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-25T06:46:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2024\/07\/og-AW-_-\u0e20\u0e32\u0e1e\u0e41\u0e0a\u0e23\u0e4c-\u0e19\u0e49\u0e2d\u0e07\u0e01\u0e2d\u0e25\u0e4c\u0e1f-\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c.png\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"378\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"\u0e04\u0e23\u0e39\u0e19\u0e49\u0e33\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0e04\u0e23\u0e39\u0e19\u0e49\u0e33\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/school.dek-d.com\/blog\/review\/posn-physics-golf\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/school.dek-d.com\/blog\/review\/posn-physics-golf\/\"},\"author\":{\"name\":\"\u0e04\u0e23\u0e39\u0e19\u0e49\u0e33\",\"@id\":\"https:\/\/school.dek-d.com\/blog\/#\/schema\/person\/e8061732124e911d6d28cc4d8b0a3aeb\"},\"headline\":\"\u0e41\u0e0a\u0e23\u0e4c\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c \u0e15\u0e34\u0e14\u0e04\u0e48\u0e32\u0e22 2 \u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\",\"datePublished\":\"2024-07-25T06:46:53+00:00\",\"dateModified\":\"2024-07-25T06:46:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/school.dek-d.com\/blog\/review\/posn-physics-golf\/\"},\"wordCount\":18,\"publisher\":{\"@id\":\"https:\/\/school.dek-d.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/school.dek-d.com\/blog\/review\/posn-physics-golf\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2024\/07\/og-AW-_-\u0e20\u0e32\u0e1e\u0e41\u0e0a\u0e23\u0e4c-\u0e19\u0e49\u0e2d\u0e07\u0e01\u0e2d\u0e25\u0e4c\u0e1f-\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c.png\",\"keywords\":[\"dekdschool\",\"\u0e15\u0e34\u0e27\u0e2a\u0e2d\u0e27\u0e19.\",\"\u0e15\u0e34\u0e27\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c\",\"\u0e15\u0e34\u0e27\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\",\"\u0e2a\u0e2d\u0e27\u0e19.\",\"\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c\",\"\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e2a\u0e2d\u0e27\u0e19.\",\"\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c\"],\"articleSection\":[\"Featured\",\"Review\",\"\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e41\u0e19\u0e30\u0e19\u0e33\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/school.dek-d.com\/blog\/review\/posn-physics-golf\/\",\"url\":\"https:\/\/school.dek-d.com\/blog\/review\/posn-physics-golf\/\",\"name\":\"\u0e41\u0e0a\u0e23\u0e4c\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c \u0e15\u0e34\u0e14\u0e04\u0e48\u0e32\u0e22 2 \u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\",\"isPartOf\":{\"@id\":\"https:\/\/school.dek-d.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/school.dek-d.com\/blog\/review\/posn-physics-golf\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/school.dek-d.com\/blog\/review\/posn-physics-golf\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2024\/07\/og-AW-_-\u0e20\u0e32\u0e1e\u0e41\u0e0a\u0e23\u0e4c-\u0e19\u0e49\u0e2d\u0e07\u0e01\u0e2d\u0e25\u0e4c\u0e1f-\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c.png\",\"datePublished\":\"2024-07-25T06:46:53+00:00\",\"dateModified\":\"2024-07-25T06:46:58+00:00\",\"description\":\"\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c \u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e42\u0e04\u0e49\u0e07\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22 \u0e21\u0e32\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e14\u0e48\u0e27\u0e19\u0e46 \u0e08\u0e32\u0e01\u0e1e\u0e35\u0e48\u0e01\u0e2d\u0e25\u0e4c\u0e1f\u0e23\u0e38\u0e48\u0e19\u0e1e\u0e35\u0e48\u0e40\u0e14\u0e47\u0e01\u0e04\u0e48\u0e32\u0e22\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22\",\"breadcrumb\":{\"@id\":\"https:\/\/school.dek-d.com\/blog\/review\/posn-physics-golf\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/school.dek-d.com\/blog\/review\/posn-physics-golf\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/school.dek-d.com\/blog\/review\/posn-physics-golf\/#primaryimage\",\"url\":\"https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2024\/07\/og-AW-_-\u0e20\u0e32\u0e1e\u0e41\u0e0a\u0e23\u0e4c-\u0e19\u0e49\u0e2d\u0e07\u0e01\u0e2d\u0e25\u0e4c\u0e1f-\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c.png\",\"contentUrl\":\"https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2024\/07\/og-AW-_-\u0e20\u0e32\u0e1e\u0e41\u0e0a\u0e23\u0e4c-\u0e19\u0e49\u0e2d\u0e07\u0e01\u0e2d\u0e25\u0e4c\u0e1f-\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c.png\",\"width\":720,\"height\":378},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/school.dek-d.com\/blog\/review\/posn-physics-golf\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/school.dek-d.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e41\u0e0a\u0e23\u0e4c\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c \u0e15\u0e34\u0e14\u0e04\u0e48\u0e32\u0e22 2 \u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/school.dek-d.com\/blog\/#website\",\"url\":\"https:\/\/school.dek-d.com\/blog\/\",\"name\":\"\u0e2a\u0e2d\u0e19\u0e25\u0e39\u0e01\u0e40\u0e02\u0e35\u0e22\u0e19\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 By Dek-D.com\",\"description\":\"\u0e04\u0e2d\u0e23\u0e4c\u0e2a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c | \u0e40\u0e01\u0e48\u0e07\u0e01\u0e27\u0e48\u0e32 \u0e14\u0e49\u0e27\u0e22\u0e40\u0e27\u0e25\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e31\u0e49\u0e19\u0e01\u0e27\u0e48\u0e32\",\"publisher\":{\"@id\":\"https:\/\/school.dek-d.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/school.dek-d.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/school.dek-d.com\/blog\/#organization\",\"name\":\"Dek-D Interactive\",\"url\":\"https:\/\/school.dek-d.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/school.dek-d.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2018\/01\/mobile_280x96-1.png\",\"contentUrl\":\"https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2018\/01\/mobile_280x96-1.png\",\"width\":280,\"height\":96,\"caption\":\"Dek-D Interactive\"},\"image\":{\"@id\":\"https:\/\/school.dek-d.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/kidcoding\/\",\"https:\/\/www.youtube.com\/user\/webdekd\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/school.dek-d.com\/blog\/#\/schema\/person\/e8061732124e911d6d28cc4d8b0a3aeb\",\"name\":\"\u0e04\u0e23\u0e39\u0e19\u0e49\u0e33\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/school.dek-d.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ddff52be616465b8b9719aba88a2156c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ddff52be616465b8b9719aba88a2156c?s=96&d=mm&r=g\",\"caption\":\"\u0e04\u0e23\u0e39\u0e19\u0e49\u0e33\"},\"url\":\"https:\/\/school.dek-d.com\/blog\/author\/prapimpan\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e41\u0e0a\u0e23\u0e4c\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c \u0e15\u0e34\u0e14\u0e04\u0e48\u0e32\u0e22 2 \u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c","description":"\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c \u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e42\u0e04\u0e49\u0e07\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22 \u0e21\u0e32\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e14\u0e48\u0e27\u0e19\u0e46 \u0e08\u0e32\u0e01\u0e1e\u0e35\u0e48\u0e01\u0e2d\u0e25\u0e4c\u0e1f\u0e23\u0e38\u0e48\u0e19\u0e1e\u0e35\u0e48\u0e40\u0e14\u0e47\u0e01\u0e04\u0e48\u0e32\u0e22\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/school.dek-d.com\/blog\/review\/posn-physics-golf\/","og_locale":"en_US","og_type":"article","og_title":"\u0e41\u0e0a\u0e23\u0e4c\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c \u0e15\u0e34\u0e14\u0e04\u0e48\u0e32\u0e22 2 \u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c","og_description":"\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c \u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e42\u0e04\u0e49\u0e07\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22 \u0e21\u0e32\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e14\u0e48\u0e27\u0e19\u0e46 \u0e08\u0e32\u0e01\u0e1e\u0e35\u0e48\u0e01\u0e2d\u0e25\u0e4c\u0e1f\u0e23\u0e38\u0e48\u0e19\u0e1e\u0e35\u0e48\u0e40\u0e14\u0e47\u0e01\u0e04\u0e48\u0e32\u0e22\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22","og_url":"https:\/\/school.dek-d.com\/blog\/review\/posn-physics-golf\/","og_site_name":"Dek-D&#039;s School","article_publisher":"https:\/\/www.facebook.com\/kidcoding\/","article_published_time":"2024-07-25T06:46:53+00:00","article_modified_time":"2024-07-25T06:46:58+00:00","og_image":[{"width":720,"height":378,"url":"https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2024\/07\/og-AW-_-\u0e20\u0e32\u0e1e\u0e41\u0e0a\u0e23\u0e4c-\u0e19\u0e49\u0e2d\u0e07\u0e01\u0e2d\u0e25\u0e4c\u0e1f-\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c.png","type":"image\/png"}],"author":"\u0e04\u0e23\u0e39\u0e19\u0e49\u0e33","twitter_card":"summary_large_image","twitter_misc":{"Written by":"\u0e04\u0e23\u0e39\u0e19\u0e49\u0e33","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/school.dek-d.com\/blog\/review\/posn-physics-golf\/#article","isPartOf":{"@id":"https:\/\/school.dek-d.com\/blog\/review\/posn-physics-golf\/"},"author":{"name":"\u0e04\u0e23\u0e39\u0e19\u0e49\u0e33","@id":"https:\/\/school.dek-d.com\/blog\/#\/schema\/person\/e8061732124e911d6d28cc4d8b0a3aeb"},"headline":"\u0e41\u0e0a\u0e23\u0e4c\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c \u0e15\u0e34\u0e14\u0e04\u0e48\u0e32\u0e22 2 \u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c","datePublished":"2024-07-25T06:46:53+00:00","dateModified":"2024-07-25T06:46:58+00:00","mainEntityOfPage":{"@id":"https:\/\/school.dek-d.com\/blog\/review\/posn-physics-golf\/"},"wordCount":18,"publisher":{"@id":"https:\/\/school.dek-d.com\/blog\/#organization"},"image":{"@id":"https:\/\/school.dek-d.com\/blog\/review\/posn-physics-golf\/#primaryimage"},"thumbnailUrl":"https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2024\/07\/og-AW-_-\u0e20\u0e32\u0e1e\u0e41\u0e0a\u0e23\u0e4c-\u0e19\u0e49\u0e2d\u0e07\u0e01\u0e2d\u0e25\u0e4c\u0e1f-\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c.png","keywords":["dekdschool","\u0e15\u0e34\u0e27\u0e2a\u0e2d\u0e27\u0e19.","\u0e15\u0e34\u0e27\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c","\u0e15\u0e34\u0e27\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c","\u0e2a\u0e2d\u0e27\u0e19.","\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c","\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e2a\u0e2d\u0e27\u0e19.","\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c"],"articleSection":["Featured","Review","\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e41\u0e19\u0e30\u0e19\u0e33"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/school.dek-d.com\/blog\/review\/posn-physics-golf\/","url":"https:\/\/school.dek-d.com\/blog\/review\/posn-physics-golf\/","name":"\u0e41\u0e0a\u0e23\u0e4c\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c \u0e15\u0e34\u0e14\u0e04\u0e48\u0e32\u0e22 2 \u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c","isPartOf":{"@id":"https:\/\/school.dek-d.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/school.dek-d.com\/blog\/review\/posn-physics-golf\/#primaryimage"},"image":{"@id":"https:\/\/school.dek-d.com\/blog\/review\/posn-physics-golf\/#primaryimage"},"thumbnailUrl":"https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2024\/07\/og-AW-_-\u0e20\u0e32\u0e1e\u0e41\u0e0a\u0e23\u0e4c-\u0e19\u0e49\u0e2d\u0e07\u0e01\u0e2d\u0e25\u0e4c\u0e1f-\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c.png","datePublished":"2024-07-25T06:46:53+00:00","dateModified":"2024-07-25T06:46:58+00:00","description":"\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c \u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e42\u0e04\u0e49\u0e07\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22 \u0e21\u0e32\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e14\u0e48\u0e27\u0e19\u0e46 \u0e08\u0e32\u0e01\u0e1e\u0e35\u0e48\u0e01\u0e2d\u0e25\u0e4c\u0e1f\u0e23\u0e38\u0e48\u0e19\u0e1e\u0e35\u0e48\u0e40\u0e14\u0e47\u0e01\u0e04\u0e48\u0e32\u0e22\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22","breadcrumb":{"@id":"https:\/\/school.dek-d.com\/blog\/review\/posn-physics-golf\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/school.dek-d.com\/blog\/review\/posn-physics-golf\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/school.dek-d.com\/blog\/review\/posn-physics-golf\/#primaryimage","url":"https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2024\/07\/og-AW-_-\u0e20\u0e32\u0e1e\u0e41\u0e0a\u0e23\u0e4c-\u0e19\u0e49\u0e2d\u0e07\u0e01\u0e2d\u0e25\u0e4c\u0e1f-\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c.png","contentUrl":"https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2024\/07\/og-AW-_-\u0e20\u0e32\u0e1e\u0e41\u0e0a\u0e23\u0e4c-\u0e19\u0e49\u0e2d\u0e07\u0e01\u0e2d\u0e25\u0e4c\u0e1f-\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c.png","width":720,"height":378},{"@type":"BreadcrumbList","@id":"https:\/\/school.dek-d.com\/blog\/review\/posn-physics-golf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/school.dek-d.com\/blog\/"},{"@type":"ListItem","position":2,"name":"\u0e41\u0e0a\u0e23\u0e4c\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e2d\u0e1a\u0e2a\u0e2d\u0e27\u0e19.\u0e1f\u0e34\u0e2a\u0e34\u0e01\u0e2a\u0e4c \u0e15\u0e34\u0e14\u0e04\u0e48\u0e32\u0e22 2 \u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c"}]},{"@type":"WebSite","@id":"https:\/\/school.dek-d.com\/blog\/#website","url":"https:\/\/school.dek-d.com\/blog\/","name":"\u0e2a\u0e2d\u0e19\u0e25\u0e39\u0e01\u0e40\u0e02\u0e35\u0e22\u0e19\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 By Dek-D.com","description":"\u0e04\u0e2d\u0e23\u0e4c\u0e2a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c | \u0e40\u0e01\u0e48\u0e07\u0e01\u0e27\u0e48\u0e32 \u0e14\u0e49\u0e27\u0e22\u0e40\u0e27\u0e25\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e31\u0e49\u0e19\u0e01\u0e27\u0e48\u0e32","publisher":{"@id":"https:\/\/school.dek-d.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/school.dek-d.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/school.dek-d.com\/blog\/#organization","name":"Dek-D Interactive","url":"https:\/\/school.dek-d.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/school.dek-d.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2018\/01\/mobile_280x96-1.png","contentUrl":"https:\/\/school.dek-d.com\/blog\/wp-content\/uploads\/2018\/01\/mobile_280x96-1.png","width":280,"height":96,"caption":"Dek-D Interactive"},"image":{"@id":"https:\/\/school.dek-d.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kidcoding\/","https:\/\/www.youtube.com\/user\/webdekd"]},{"@type":"Person","@id":"https:\/\/school.dek-d.com\/blog\/#\/schema\/person\/e8061732124e911d6d28cc4d8b0a3aeb","name":"\u0e04\u0e23\u0e39\u0e19\u0e49\u0e33","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/school.dek-d.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ddff52be616465b8b9719aba88a2156c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ddff52be616465b8b9719aba88a2156c?s=96&d=mm&r=g","caption":"\u0e04\u0e23\u0e39\u0e19\u0e49\u0e33"},"url":"https:\/\/school.dek-d.com\/blog\/author\/prapimpan\/"}]}},"_links":{"self":[{"href":"https:\/\/school.dek-d.com\/blog\/wp-json\/wp\/v2\/posts\/91967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/school.dek-d.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/school.dek-d.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/school.dek-d.com\/blog\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/school.dek-d.com\/blog\/wp-json\/wp\/v2\/comments?post=91967"}],"version-history":[{"count":16,"href":"https:\/\/school.dek-d.com\/blog\/wp-json\/wp\/v2\/posts\/91967\/revisions"}],"predecessor-version":[{"id":91987,"href":"https:\/\/school.dek-d.com\/blog\/wp-json\/wp\/v2\/posts\/91967\/revisions\/91987"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/school.dek-d.com\/blog\/wp-json\/wp\/v2\/media\/91979"}],"wp:attachment":[{"href":"https:\/\/school.dek-d.com\/blog\/wp-json\/wp\/v2\/media?parent=91967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/school.dek-d.com\/blog\/wp-json\/wp\/v2\/categories?post=91967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/school.dek-d.com\/blog\/wp-json\/wp\/v2\/tags?post=91967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}